{"id":144760,"date":"2021-02-06T11:00:29","date_gmt":"2021-02-06T10:00:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/giornata-contro-lepilessia-a-scalea-la-panchina-viola-dellaice\/"},"modified":"2023-01-16T17:27:24","modified_gmt":"2023-01-16T16:27:24","slug":"393526-giornata-contro-lepilessia-a-scalea-la-panchina-viola-dellaice","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/393526-giornata-contro-lepilessia-a-scalea-la-panchina-viola-dellaice\/","title":{"rendered":"Giornata contro l&#8217;epilessia, a Scalea la panchina viola dell&#8217;Aice"},"content":{"rendered":"<h4>Luned\u00ec prossimo, 8 febbraio nell\u2019ambito della giornata internazionale contro l\u2019epilessia, l&#8217;amministrazione comunale inaugurer\u00e0 la panchina viola<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SCALEA &#8211; Si tratta di un gesto simbolico &#8211; \u00e8 scritto in un comunicato &#8211; che la maggioranza guidata dal sindaco Perrotta ha voluto prendere in considerazione con piena convinzione sotto l&#8217;impulso del presidente regionale dell\u2019Aice Calabria Carmine Galiano, giovane cittadino scaleoto che gi\u00e0 da anni porta avanti iniziative di sensibilizzazione sul tema dell&#8217;epilessia. L&#8217;iniziativa che gode del patrocinio del Comune di Scalea e della Fondazione epilessia LICE, vedr\u00e0 oltre all&#8217;inaugurazione della panchina, l&#8217;illuminazione di viola della Torre Talao, simbolo della citt\u00e0 di Scalea, come gi\u00e0 accaduto nel 2018.<br \/>\n&#8220;La manifestazione del prossimo 8 febbraio segue idealmente quella del 12 febbraio 2018 quando, grazie all\u2019iniziativa dell\u2019AICE Calabria Associazione Italiana contro l&#8217;epilessia e con la collaborazione della FIE Federazione Italiana Epilessia, grazie ai medici del territorio e con il patrocinio del comune di Scalea &#8211; racconta Galiano &#8211; riuscii ad organizzare il primo convegno sull&#8217;epilessia presso la sala consiliare del comune di Scalea dal titolo: Noi ci siamo. L\u2019evento del prossimo 8 febbraio \u00e8 un segnale importante per la nostra comunit\u00e0 &#8211; prosegue Galiano &#8211; e per tutte le famiglie che convivono con la malattia verso la quale \u00e8 necessaria una approfondita conoscenza per consentire a chi ne soffre e alle famiglie il corretto supporto e l\u2019inclusivit\u00e0 necessaria a far vivere in maniera normale un disagio che pu\u00f2 essere molto difficile da gestire. Per l\u2019evento simbolico del prossimo 8 febbraio che si svolger\u00e0 in pieno rispetto delle norme anticovid &#8211; conclude Galiano &#8211; voglio ringraziare tutta l&#8217;amministrazione comunale di Scalea per la sensibilit\u00e0 dimostrata ed in particolare il Sindaco Giacomo Perrotta, il Vicesindaco con delega alle politiche sociali Annalisa Alfano, l&#8217;Assessore ai lavori pubblici Renato Lombardo, e le associazioni AIDM Sezione di Diamante Riviera dei Cedri, la Pro Loco Scalea e l\u2019associazione Banca del Tempo Scalea per il loro sostegno e contributo fattivo&#8221;.<br \/>\n&#8220;Iniziative di questo tenore trovano il nostro totale appoggio &#8211; ha spiegato il sindaco Perrotta &#8211; perch\u00e9 rappresentano momenti di importanti prese di coscienza e di coinvolgimento della comunit\u00e0 su problemi intorno ai quali \u00e8 fondamentale la conoscenza. Solo cos\u00ec &#8211; ha concluso il sindaco Perrotta &#8211; si pu\u00f2 essere pronti ad acquisire gli strumenti necessari ad affrontare queste tematiche non solo dal punto di vista medico ma, soprattutto, sotto il profilo sociale e culturale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Luned\u00ec prossimo, 8 febbraio nell\u2019ambito della giornata internazionale contro l\u2019epilessia, l&#8217;amministrazione comunale inaugurer\u00e0 la panchina viola<\/p>\n","protected":false},"author":56,"featured_media":144761,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-144760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144760"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144761"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}