{"id":144772,"date":"2021-02-06T15:11:08","date_gmt":"2021-02-06T14:11:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/buon-cosenza-ma-il-marulla-resta-tabu-sciaudone-e-mora-confezionano-l1-a-1\/"},"modified":"2023-01-16T17:27:24","modified_gmt":"2023-01-16T16:27:24","slug":"393550-buon-cosenza-ma-il-marulla-resta-tabu-sciaudone-e-mora-confezionano-l1-a-1","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/393550-buon-cosenza-ma-il-marulla-resta-tabu-sciaudone-e-mora-confezionano-l1-a-1\/","title":{"rendered":"Buon Cosenza, ma il Marulla resta tab\u00f9. Sciaudone e Mora confezionano l&#8217;1 a 1"},"content":{"rendered":"<h4>Ennesimo pareggio casalingo per un Cosenza che ha mostrato comunque importanti segnali soprattutto in attacco. Primo tempo equilibrato chiuso in vantaggio con la rete di Sciaudone. Nel secondo tempo Spal a testa bassa che pareggia con Mora, trova sulla sua strada un grande Falcone e recrimina per un goal annullato ingiustamente <!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;<strong> Il Cosenza deve rinviare ancora una volta l&#8217;appuntamento con la prima vittoria casalinga<\/strong>, anche se questa volta il pareggio maturato al Marulla, contro un avversario forte e di qualit\u00e0 come la Spal, \u00e8 di sicuro un punto guadagnato pi\u00f9 che perso, considerando che Falcone \u00e8 stato il migliore in campo e che gli ospiti possono recriminare su un goal regolarissimo annullato per un fuorigioco inesistente. Finisce dunque 1 a 1 un match bello, combattuto nel quale i rossoblu hanno comunque mostrato evidenti passi in avanti nella costruzione del gioco, <strong>trascinati da un super Tremolada<\/strong>, sempre al centro delle azioni d&#8217;attacco e da un Carretta ispirato. Primo tempo equilibrato, <strong>spezzato dal vantaggio del Cosenza al minuto 25&#8242;<\/strong> e realizzato da Sciaudone che insacca di piatto l&#8217;assist di Carretta sporcato da Tremolada. Nel secondo tempo \u00e8 un&#8217;altra partita. La Spal attacca a testa basta trovando sulla sua strada un grande Falcone. <strong>Il pareggio, meritato, arriva al minuto 57&#8242; con l&#8217;inzuccata di Mora <\/strong>che corregge in rete la spizzata di Missiroli. Il Cosenza replica con la <strong>conclusione di Tremolada <\/strong>ma sono gli ospiti a sfiorare a ripetizione il vantaggio con Valoti, Strefezza, Dickamann e Moro. Ma Falcone \u00e8 in stato di grazia e alza la saracinesca. E quando il pallone entra in rete, arriva la topica dell&#8217;assistente che annulla per fuorigioco un goal regolare. I rossobliu stringono i denti e portano a casa un pareggio, l&#8217;ennesimo, che questa volta vale come una vittoria.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/12258\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-393590\" src=\"https:\/\/quicosenza.it\/news\/12258\" alt=\"\" width=\"584\" height=\"364\" title=\"\"><\/a><\/p>\n<h4>Buona Spal, ma i rossoblu colpiscono con Sciaudone<\/h4>\n<p>Squadra che vince non si cambia. In attesa che Mbakogu e Trotta recuperino la migliore condizione fisica, Occhiuzzi va sul sicuro e schiera in campo la stessa formazione che sabato scorso ha espugnato Chiavari, affidando le chiavi dell&#8217;attacco al tridente formato da Tremolada, Gliozzi e Carretta. Gara subito vivace con la <strong>conclusione di Valoti bloccata da Falcone<\/strong> e le proteste degli ospiti per un<strong> presunto tocco di mani in area di Legittimo<\/strong> sulla conclusione da fuori di Dickmann. Il Cosenza replica al 13&#8242; con la conclusione a giro di Sciaudone dal limite che termina tra le braccia di Berisha. Decisamente pi\u00f9 insidioso il<strong> destro dal vertice di Strefezza<\/strong> che indirizza sul secondo palo con la palla che si perde di un nulla alla destra di Falcone. Al 21&#8242; ancora gli ospiti pericolosi con Seck. Il lungo attaccante senegalese controlla in area e spara sul primo palo, pallone alto. \u00c8 la Spal a menare le danze con i rossoblu che provano a coprire tutti gli spazi e colpire di rimessa. E<strong> al 26&#8242; una ripartenza perfetta porta al vantaggio del Cosenza<\/strong>. Carretta dal fondo entra in area e mette in mezzo, pallone toccato da Tremolada che fornisce un assist involontario per l&#8217;accorrente Sciaudone che di piatto fa secco Berisha. Il vantaggio ringalluzzisce i rossoblu che al 33&#8242; vanno ancora al tiro con un <strong>diagonale di Carretta<\/strong> che per\u00f2 non trova l&#8217;effetto a rientrare e il pallone si perde sul fondo. \u00c8 questa l&#8217;ultima emozione della prima frazione si chiude con il Cosenza avanti di una rete.<\/p>\n<h4>Tanta Spal. Pareggio di Morra e goal annullato a Moro<\/h4>\n<p>La ripresa riparte con gli stessi 22&#8242; del primo tempo e con la Spal che attacca subito a testa basta alla ricerca del pari. Al 54&#8242; incursione di Ranieri e <strong>diagonale a botta sicura<\/strong> che trova la grande respinta di Falcone che si salva con i piedi. Due minuti dopo<strong> piattone di Mora dal limite<\/strong> e pallone deviato in angolo. <strong>Sul corner arriva il pareggio<\/strong>: Strefezza crossa in area, Missiroli fa la sponda per l&#8217;accorrente Mora che di testa spedisce in rete. Il Cosenza accusa il colpo e rischia di capitolare ancora sulla <strong>conclusione di Paloschi<\/strong> che fa la barba al palo e sul <strong>destro al volo di Valoti<\/strong> in area che trova la grandissima risposta di Falcone. Occhiuzzi richiama Gliozzi per Trotta. I rossoblu si riorganizzano e tornano a fasi vedere in attacco con Carretta ma soprattutto con la <strong>conclusione di Tremolada<\/strong> che Berisha respinge con i pugni. La partita cambia fisionomia con le due squadre spaccate a centrocampo e spazi che si aprono da una parte e dell&#8217;altra. Tremolada di tacco libera Trotta che prova a indirizzare sul secondo palo, pallone che non gira bloccato da Berisha. Al minuto 80&#8242; <strong>Tremolada ci prova direttamente su punizione<\/strong>, pallone sul primo palo e grande risposta di Berisha. Dall&#8217;altra parte <strong>l&#8217;episodio che far\u00e0 discutere<\/strong>: Falcone respinge la conclusione di Strefezza, pallone che finisce a Moro che da due passi insacca. <strong>Goal annullato per fuorigioco che non c&#8217;\u00e8<\/strong>. Al minuto 86<strong>&#8216; nuovo grande intervento di Falcone<\/strong> ancora su Moro. Il Cosenza soffre e rischia ancora suk destro di Dickman che accarezza il palo e termina sul fondo. \u00c8 l&#8217;ultima occasione di un\u00a0 match che si conclude in parit\u00e0, l&#8217;ennesimo per il Cosenza.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COSENZA CALCIO (3-4-1-2)<\/strong>: Falcone, Gerbo, Idda, Carretta, Sciaudone, Legittimo, Vera (87&#8242; Corsi), Tremolada (84&#8242; Bahlouli), Gliozzi (59&#8242; Trotta), Ingrosso, Petrucci<br \/>\n<strong>Panchina<\/strong>: Matosevic, Saracco, Corsi, Bahlouli, Schiavi, Sacko, Antizoulas, Schiavi, Ba, Kone, Trotta, Sueva<br \/>\n<strong>Allenatore<\/strong>: Roberto Occhiuzzi<\/p>\n<p><strong>SPAL (3-5-2): <\/strong>Berisha, Ranieri, Missiroli (78&#8217;Segre), Valoti, Paloschi, Mora (71&#8242; Esposito) , Okoli, Vicari, Strefezza, Dickmann, Seck (71&#8242; Moro)<strong><br \/>\nPanchina: <\/strong>Thiam,\u00a0 Gomis, Tomovic, Segre, Esposito, Spaltro, Sala, Moro, Tumminiello<br \/>\n<strong>Allenatore:<\/strong> Pasquale Marino<\/p>\n<p><strong>Arbitro:\u00a0<\/strong>Signor Eugenio Abbattista di Molfetta<br \/>\n<strong>Assistenti:<\/strong>\u00a0Signori Daisuke Emanuele Yoshikawa di Roma 1 e Francesca Di Monte di Chieti<br \/>\n<strong>IV Uomo:<\/strong> Signor Antonio Rapuano di Rimini<\/p>\n<p><strong>Ammoniti: <\/strong>Gerbo (C), Valoti\u00a0 (S), Okoli (S)<br \/>\n<strong>Espulsi:<\/strong><\/p>\n<p><strong>Angoli: <\/strong>2-7<br \/>\n<strong>Recupero: <\/strong>1&#8242; p.t. &#8211; 3&#8242; s.t.<\/p>\n<p><strong>Note:<\/strong> Pomeriggio soleggiato a Cosenza con una temperatura di 18 gradi. Terreno del Marulla in ottime condizioni. Gara a porte chiuse per le disposizioni anti-Covid emanate dal Governo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ennesimo pareggio casalingo per un Cosenza che ha mostrato comunque importanti segnali soprattutto in attacco. Primo tempo equilibrato chiuso in vantaggio con la rete di Sciaudone. Nel secondo tempo Spal a testa bassa che pareggia con Mora, trova sulla sua strada un grande Falcone e recrimina per un goal annullato ingiustamente<\/p>\n","protected":false},"author":23,"featured_media":144773,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-144772","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144772","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144772"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144772\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144773"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144772"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144772"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144772"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}