{"id":144861,"date":"2021-02-09T08:11:00","date_gmt":"2021-02-09T07:11:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrolibero-legittima-la-procedura-di-affidamento-per-lilluminazione-pubblica\/"},"modified":"2023-01-16T17:27:31","modified_gmt":"2023-01-16T16:27:31","slug":"393784-castrolibero-legittima-la-procedura-di-affidamento-per-lilluminazione-pubblica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/393784-castrolibero-legittima-la-procedura-di-affidamento-per-lilluminazione-pubblica\/","title":{"rendered":"Castrolibero, legittima la procedura di affidamento per l&#8217;illuminazione pubblica"},"content":{"rendered":"<h4>Il TAR della Calabria, con sentenza n. 259 dell\u20198 febbraio 2021, ha respinto il ricorso proposto dalla societ\u00e0 ex affidataria dell\u2019appalto di realizzazione e gestione dell\u2019illuminazione nel Comune di Castrolibero<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CASTROLIBERO (CS) &#8211; Il Tar ha accolto le tesi difensive dell\u2019avv. Oreste Morcavallo e ha respinto il ricorso proposto dalla societ\u00e0 ex affidataria dell\u2019appalto di realizzazione e gestione dell\u2019illuminazione pubblica nel Comune di Castrolibero. Con contratto di appalto il Comune aveva affidato alla Societ\u00e0 ricorrente la gestione integrata degli <strong>impianti elettrici, termici, antincendio e di pubblica illuminazione di propriet\u00e0 comunale, per la durata di 25 anni.<\/strong><\/p>\n<p>Nel corso dell\u2019esecuzione del contratto, la stessa societ\u00e0, \u00e8 stata attinta da un provvedimento interdittivo antimafia adottato dalla Prefettura di Roma. Con successivo decreto \u2013 a seguito di interlocuzioni tra il Comune e la Prefettura \u2013 il Prefetto ha disposto la straordinaria e temporanea gestione di tale contratto da parte della medesima societ\u00e0 per il <strong>tempo strettamente necessario ad individuare un altro interlocutore<\/strong> con procedura ad evidenza pubblica e comunque per un periodo non superiore ad anni due, conferendo l\u2019incarico per la straordinaria e temporanea gestione della stessa ad un commissario incaricato di sollecitare, in coerenza con le indicazioni fornite dall\u2019ANAC, le stazioni appaltanti affinch\u00e9 avviassero i provvedimenti volti al cambio dell\u2019operatore economico per l\u2019affidamento dei lavori e la gestione dei servizi oggetto dei contratti ancora in essere in gestione temporanea e straordinaria.<\/p>\n<p>Con successiva determina il Comune di Castrolibero ha poi disposto la rescissione del contratto e bandito la procedura di gara per l\u2019affidamento del servizio di \u201cConduzione in esercizio e manutenzione ordinaria della rete di pubblica illuminazione e degli impianti termici ed elettrici degli edifici comunali\u201d, mediante affidamento diretto, previa valutazione di almeno <strong>5 operatori economici<\/strong> individuati attraverso elenchi di operatori economici, nel rispetto di un criterio di rotazione degli inviti. Avverso all&#8217;atto l\u2019ex affidatario ha proposto il ricorso dinnanzi al TAR Calabria richiedendo un indennizzo milionario.<\/p>\n<p>L\u2019amministrazione comunale di Castrolibero, con l\u2019Avv. Oreste Morcavallo ha rilevato l\u2019infondatezza del ricorso ed il TAR all&#8217;esito dell&#8217;udienza ha respinto il ricorso e stabilito innovativi principi relativamente agli effetti dell\u2019interdittiva in rapporto alle gare di appalto. Pertanto la decisione del TAR conferma la piena legittimit\u00e0 della procedura indetta dal Comune di Castrolibero che pu\u00f2 spiegare i suoi effetti garantendo la regolare manutenzione del servizio di illuminazione comunale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il TAR della Calabria, con sentenza n. 259 dell\u20198 febbraio 2021, ha respinto il ricorso proposto dalla societ\u00e0 ex affidataria dell\u2019appalto di realizzazione e gestione dell\u2019illuminazione nel Comune di Castrolibero<\/p>\n","protected":false},"author":42,"featured_media":144862,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[564],"tags":[],"class_list":["post-144861","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-castrolibero"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144861","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144861"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144861\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144862"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144861"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144861"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144861"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}