{"id":144995,"date":"2021-02-14T18:00:32","date_gmt":"2021-02-14T17:00:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/intesa-tra-confindustria-cosenza-e-unical-su-innovazione-e-sistema-imprenditoriale\/"},"modified":"2023-01-16T17:27:39","modified_gmt":"2023-01-16T16:27:39","slug":"394166-intesa-tra-confindustria-cosenza-e-unical-su-innovazione-e-sistema-imprenditoriale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/394166-intesa-tra-confindustria-cosenza-e-unical-su-innovazione-e-sistema-imprenditoriale\/","title":{"rendered":"Intesa tra Confindustria Cosenza e Unical su innovazione e sistema imprenditoriale"},"content":{"rendered":"<h4>Marted\u00ec sar\u00e0 siglato un protocollo d\u2019intesa tra Confindustria Cosenza e Universit\u00e0 della Calabria per la diffusione dell\u2019innovazione e la valorizzazione del sistema imprenditoriale<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L\u2019accordo sar\u00e0 presentato marted\u00ec 16 febbraio 2021 alle ore 11 e ha l&#8217;obiettivo di rafforzare le modalit\u00e0 di collaborazione per mettere in rete e valorizzare le competenze e le esperienze imprenditoriali, di ricerca e di innovazione presenti sul territorio. La firma avverr\u00e0 marted\u00ec prossimo 16 febbraio, nel corso di una conferenza online, con inizio alle ore 11. Confindustria Cosenza e Unical, attraverso il suo incubatore <strong>TechNest<\/strong>, si impegneranno a collaborare in attivit\u00e0 e programmi per favorire azioni come:<\/p>\n<p>&#8211; la realizzazione di progetti di innovazione per le imprese mediante l\u2019apporto di conoscenze da parte di startup innovative e gruppi di ricerca;<br \/>\n&#8211; la nascita e lo sviluppo di startup innovative attraverso l\u2019impiego di competenze manageriali e di mercato;<br \/>\n&#8211; l\u2019accesso a finanziamenti privati da parte delle startup anche tramite accordi con operatori specializzati (Banche, Fondi di seed e venture capital, investitori privati, ecc.).<\/p>\n<p>Le azioni previste dal <strong>Protocollo, di durata quinquennale<\/strong>, partiranno subito con le prime attivit\u00e0 gi\u00e0 concordate e che saranno illustrate nel corso della conferenza. Si tratta delle iniziative: \u201c<strong>Sportello startup<\/strong>\u201d che prevede assistenza e servizi gratuiti da parte degli uffici di Confindustria Cosenza a favore delle imprese dell\u2019incubatore TechNest dell\u2019Unical; coinvolgimento di Confindustria Cosenza nei percorsi di formazione d\u2019impresa Unical come il \u201c<strong>Contamination Lab\u201d<\/strong>; <strong>\u201cAdotta una startup\u201d<\/strong> che consiste in servizi di mentorship per startup innovative, da costituire o gi\u00e0 costituite, grazie al coinvolgimento di imprenditori esperti; webinar su Industria 4.0 tenuti da startup e spin-off Unical per le aziende del sistema Confindustria.<\/p>\n<p>Interverranno il presidente di Confindustria Cosenza <strong>Fortunato Amarelli, <\/strong>il Magnifico Rettore dell\u2019Universit\u00e0 della Calabria <strong>Nicola Leone <\/strong>mentre i \u00a0lavori, moderati dal direttore di Confindustria Cosenza, <strong>Rosario Branda. <\/strong>Previste le testimonianze di spin off e start up dell\u2019Unical, a cura di Carmine Maletta dell\u2019impresa \u201c2SMArtEST\u201d e di Giuseppe Luci per \u201cMediCal\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marted\u00ec sar\u00e0 siglato un protocollo d\u2019intesa tra Confindustria Cosenza e Universit\u00e0 della Calabria per la diffusione dell\u2019innovazione e la valorizzazione del sistema imprenditoriale<\/p>\n","protected":false},"author":23,"featured_media":144996,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,7],"tags":[19],"class_list":["post-144995","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=144995"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/144995\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/144996"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=144995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=144995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=144995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}