{"id":145107,"date":"2021-02-12T18:48:52","date_gmt":"2021-02-12T17:48:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/guarascio-lassenza-dei-tifosi-pesa-alla-classifica-e-alle-casse-occhiuzzi-ci-salveremo\/"},"modified":"2023-01-16T17:27:47","modified_gmt":"2023-01-16T16:27:47","slug":"394448-guarascio-lassenza-dei-tifosi-pesa-alla-classifica-e-alle-casse-occhiuzzi-ci-salveremo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/394448-guarascio-lassenza-dei-tifosi-pesa-alla-classifica-e-alle-casse-occhiuzzi-ci-salveremo\/","title":{"rendered":"Guarascio &#8220;l&#8217;assenza dei tifosi pesa alla classifica e alle casse&#8221;. Occhiuzzi &#8220;ci salveremo&#8221;"},"content":{"rendered":"<h4>Presentazione dei nuovi calciatori arrivati nel mercato di gennaio e conferenza stampa alla quale ha partecipato anche il presidente Guarascio, l&#8217;allenatore Occhiuzzi e il DS Trinchera &#8220;rinnovo? Pensiamo a salvare il Cosenza&#8221;. <strong>Mbakogu &#8220;sono tre anni che il Cosenza mi cercava. La condizione? Sto bene&#8221;.\u00a0<\/strong><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0Si \u00e8 svolta nel pomeriggio di oggi, all&#8217;interno della sala stampa \u201cDonato Bergamini\u201d al \u201cSan Vito-Marulla\u201d, la conferenza stampa di <strong>presentazione dei nuovi calciatori<\/strong>, arrivati durante il mercato di riparazione: Tremolada, Gerbo, Trotta, Mbakogu, Crecco e il difensore greco Antzoulas. Presentazione alla quale ha preso parte anche il presidente del Cosenza Eugenio Guarascio, accompagnato dal direttore sportivo Trinchera e dal tecnico Roberto Occhiuzzi. Al numero uno del club, inevitabilmente, sono state formulate la maggior parte delle domande a cominciare dalla situazione di classifica del Cosenza nella stagione in corso, alla cessione di Baez e al futuro del DS Trinchera.<\/p>\n<p>Il presidente del Cosenza, che ha ringraziato i calciatori che hanno lasciato la squadra, ha rimarcato come sia pesata e stia ancora pesando molto l&#8217;assenza del pubblico dagli spalti &#8220;<strong>se ci fosse stato il pubblico avremmo avuto 5-6 punti in pi\u00f9<\/strong>, perch\u00e8 proprio grazie al nostro pubblico che siamo arrivati fin qui. Ci sono <strong>moltissimi costi per le squadre del sud<\/strong>, come le tantissime trasferte al nord che pesano e non poco sulle casse della societ\u00e0&#8221;. E qui arriva la domanda sulla cessione di Baez e se verranno reinvestiti gli introiti derivanti dalla vendita (fruttata circa 600mila euro) compresa l&#8217;imminente operazione di valorizzazione di Falcone <strong>&#8220;amministriamo il Cosenza in una maniera oculata &#8211; <\/strong>\u00a0ha risposto Guarascio &#8211; e <strong>i bilanci sono fatti di entrate e uscite<\/strong>. Siamo molto attenti su questo&#8221;.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/12299\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-394465\" src=\"https:\/\/quicosenza.it\/news\/12299\" alt=\"\" width=\"575\" height=\"383\" title=\"\"><\/a><\/p>\n<p>Si parla poi di mercato &#8220;non \u00e8 pensabile un mercato per un mese e mezzo, \u00e8 chiaro che tutte le operazione vengono concretizzate verso la fine della sessione.<strong> La Serie B ha alzato l\u2019asticella<\/strong>. Mentre lo scorso anno molti campioni sono andati in A adesso <strong>molti campioni sono scesi in Serie B<\/strong>, questa categoria adesso sembra un A2. Abbiamo avuto qualche difficolt\u00e0 perch\u00e9 devi fare sempre i conti con squadre che sono abbastanza attrezzate. <strong>Allargare il parco giocatori di propriet\u00e0?<\/strong> Questa \u00e8 la solita storia, anche in A si prendono calciatori in prestito. Il calcio sta cambiando, chi ora decide sono anche gli stessi calciatori. Rinnovo Sueva? Con Gianluigi siamo in sintonia, \u00e8 una questione di ore. Obiettivo?<strong> Lo dice la mia storia calcistica, aggiungere altro \u00e8 superfluo<\/strong>.\u201d<\/p>\n<p>La parola passa poi al DS Trinchera: \u201c<strong>Rinnovo? E\u2019 una giornata dedicata ai ragazzi appena arrivati, sono sicuro contribuiranno alla salvezza<\/strong>. C\u2019\u00e8 poco da aggiungere, con il presidente sono sempre stato in sintonia e sono orgoglioso di essere a Cosenza, lo dico a scanso di equivoci. Sono un privilegiato ad essere al Cosenza cos\u00ec da mettere in mostra le mie qualit\u00e0. Al di l\u00e0 dei programmi che possono essere diversi da come uno ci si aspetta, \u00e8 giusto dire che<strong> ho il dovere umano e abbiamo un obiettivo da raggiungere, che \u00e8 la salvezza del Cosenza<\/strong>. Poi a fine stagione ci metteremo a tavolino come due persone che si rispettano e tutto avverr\u00e0 in un modo spontaneo. Io a Cosenza mi trovo benissimo.\u201d<\/p>\n<p><strong>Il tecnico Occhiuzzi<\/strong> , che si \u00e8 detto soddisfatto degli innesti di gennaio, ha rimarcato la grande felicit\u00f2 per &#8220;<strong>l&#8217;opportunit\u00e0 che mi hanno dato ad allenare il Cosenza. <\/strong>La societ\u00e0 mi ha messo a disposizione una rosa per me forte. Se qualcuno non \u00e8 riuscito a rendere, la colpa \u00e8 anche mia. Adesso voglio trasformare questa fiducia in punti. Sono questi che di danno la felicit\u00e0 e ti permettono di crescere, <strong>vi assicuro che da adesso ho un solo pensiero che \u00e8 rivolto al campo<\/strong>. Se l&#8217;anno scorso ho fatto una grande salvezza \u00e8 perch\u00e9 avevo una squadra forte, cos\u00ec come riusciremo ad ottenerla anche quest&#8217;anno. <strong>Luned\u00ec il derby con la Reggina<\/strong> che vale una mezza fetta di salvezza &#8220;stiamo preparando la gara al meglio, voglio regalare una bellissima serata ai tifosi. Percorso? <strong>A me i complimenti non piacciono<\/strong>, nel calcio ci si deve confermare sempre. <strong>L&#8217;allenatore ha una responsabilit\u00e0 grande<\/strong> nei confronti della societ\u00e0, dei tifosi e dei calciatori stessi, che devono vedere nell&#8217;allenatore la loro base dove si devono aggrappare in caso di difficolt\u00e0\u201d.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/12300\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-394466\" src=\"https:\/\/quicosenza.it\/news\/12300\" alt=\"\" width=\"509\" height=\"339\" title=\"\"><\/a><\/p>\n<p>Parola poi ai nuovi arrivi in casa rossoblu.\u00a0<strong>Tremolada:<\/strong> \u201c\u00e8 stato semplice scegliere il Cosenza, conoscevo la storia di questo club anche grazie allo scorso anno dopo l\u2019impresa della salvezza. Sono contento di essere qui in Calabria. Cosa \u00e8 successo a Pordenone? Non ne voglio parlare sono qui e lavoro per questa squadra.\u201d<\/p>\n<p><strong>Gerbo:<\/strong> \u201cCosenza \u00e8 una piazza importante, le idee che il mister sviluppa sono state determinanti nella scelta di questa squadra. Credo fortemente nella salvezza. Mi piace questa nuova posizione, gi\u00e0 dalle prime uscite ho ricordato molto il modo di giocare di Stroppa.\u201d<\/p>\n<p><strong>Crecco<\/strong>: \u201cMi piace l\u2019idea che il mister cerca di darci, il compagno non si trova mai da solo e so che mi trover\u00f2 bene. Sono un ragazzo che pu\u00f2 fare pi\u00f9 ruoli, sar\u00f2 a disposizione del mister. Il Cosenza adesso \u00e8 il mio presente, spero di ripagare la loro stima.\u201d<\/p>\n<p><strong>Mbakogu<\/strong>: \u201csono tre anni che il direttore cerca di portarmi qua. Venivo da sei mesi in cui non giocavo e tra tutte le squadra ho scelto Cosenza perch\u00e9 so la stima del direttore che ha nei miei confronti, questo per me \u00e8 importantissimo. Condizione? Sto bene, sto lavorando ma \u00e8 normale dopo sei mesi di stop che la condizione non sia ottimale. Pronto per entrare al derby e segnare? Sono prontissimo per luned\u00ec\u201d<\/p>\n<p><strong>Trotta<\/strong>: \u201csto migliorando giorno dopo giorno, marted\u00ec ho fatto 90\u2019 minuti e non accadeva da tempo. Adesso dobbiamo solo lavorare per arrivare in poco tempo al 100% della condizione. Voglio dare una mano a questa squadra. Qui ho trovato un gruppo fantastico e spero di ritrovare la forma ottimale. La squadra ha fatto un\u2019ottima impressione, mi piace molto l\u2019idea di gioco del gruppo. La cosa che vuole il mister \u00e8 quella di giocare la palla per creare pi\u00f9 occasioni in avanti e quasi sempre ci riusciamo.\u201d<\/p>\n<p><strong>Antzoulas:<\/strong> \u201cSono molto felice di essere qui per la fiducia che mi ha dato la societ\u00e0. Voglio crescere con la squadra per aiutarla a raggiungere gli obiettivi prefissato. Spero di essere pronto per quando il mister punter\u00e0 su di me.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Presentazione dei nuovi calciatori arrivati nel mercato di gennaio e conferenza stampa alla quale ha partecipato anche il presidente Guarascio, l&#8217;allenatore Occhiuzzi e il DS Trinchera &#8220;rinnovo? Pensiamo a salvare il Cosenza&#8221;. Mbakogu &#8220;sono tre anni che il Cosenza mi cercava. La condizione? Sto bene&#8221;.\u00a0<\/p>\n","protected":false},"author":24,"featured_media":145108,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-145107","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/24"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=145107"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145107\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/145108"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=145107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=145107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=145107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}