{"id":145191,"date":"2021-02-15T10:42:42","date_gmt":"2021-02-15T09:42:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ha-violato-il-divieto-di-avvicinamento-e-minacciato-unamica-dellex-arrestato-25enne-di-corigliano\/"},"modified":"2023-01-16T17:27:52","modified_gmt":"2023-01-16T16:27:52","slug":"394699-ha-violato-il-divieto-di-avvicinamento-e-minacciato-unamica-dellex-arrestato-25enne-di-corigliano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/394699-ha-violato-il-divieto-di-avvicinamento-e-minacciato-unamica-dellex-arrestato-25enne-di-corigliano\/","title":{"rendered":"Viola divieto di avvicinamento e minaccia l&#8217;amica dell&#8217;ex, arrestato a Corigliano"},"content":{"rendered":"<h4>Il ragazzo, un venticinquenne coriglianese, \u00e8 accusato di rapina e violazione del divieto di avvicinamento alla parte offesa<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CORIGLIANO ROSSANO (CS) &#8211; Ha violato il divieto di avvicinamento all&#8217;ex compagna recandosi nei pressi della sua abitazione, ma non per cercare la donna bens\u00ec per minacciare una sua amica, responsabile, a suo dire, di averlo fotografato mentre danneggiava l&#8217;auto di una terza donna con la quale l&#8217;uomo aveva avuto una relazione. Un giovane di 25 anni \u00e8 stato arrestato e posto ai domiciliari dai carabinieri di Corigliano in esecuzione di un&#8217;ordinanza di aggravamento della misura cautelare emessa dal gip di Castrovillari, su richiesta della Procura, con l&#8217;accusa di rapina e violazione del divieto di avvicinamento alla parte offesa.<\/p>\n<p>Il 25enne ha raggiunto l&#8217;amica della donna, che era vicino l&#8217;abitazione della sua ex, e le ha chiesto di cancellare le foto che lo ritraevano mentre danneggiava un&#8217;auto parcheggiata, di propriet\u00e0 di un&#8217;altra sua ex. Al rifiuto della donna, l&#8217;ha aggredita e le ha sottratto il cellulare, che ha distrutto gettandolo a terra. L&#8217;uomo, in passato, aveva gi\u00e0 violato la misura del divieto di avvicinamento alla ex recandosi nell&#8217;abitazione della donna dove aveva danneggiato una porta.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il ragazzo, un venticinquenne coriglianese, \u00e8 accusato di rapina e violazione del divieto di avvicinamento alla parte offesa<\/p>\n","protected":false},"author":56,"featured_media":145192,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-145191","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=145191"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145191\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/145192"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=145191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=145191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=145191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}