{"id":145502,"date":"2021-02-21T22:11:50","date_gmt":"2021-02-21T21:11:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-cosenza-cade-3-a-1-a-lecce-e-affonda-in-classifica-ma-il-rigore-del-2-a-1-e-un-regalo\/"},"modified":"2023-01-16T17:28:13","modified_gmt":"2023-01-16T16:28:13","slug":"395515-il-cosenza-cade-3-a-1-a-lecce-e-affonda-in-classifica-ma-il-rigore-del-2-a-1-e-un-regalo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/395515-il-cosenza-cade-3-a-1-a-lecce-e-affonda-in-classifica-ma-il-rigore-del-2-a-1-e-un-regalo\/","title":{"rendered":"Il Cosenza cade 3 a 1 a Lecce e affonda in classifica. Ma il rigore del 2 a 1 \u00e8 un regalo"},"content":{"rendered":"<h4>Gara equilibrata sbloccata di testa da Gliozzi e pareggiata dopo 3&#8242; minuti dal rigore da Coda. Ma nel secondo tempo Giua assegna un secondo rigore inesistente al Lecce che chiude il match con il tris firmato da Meccariello. Per il Cosenza una sconfitta pesante con la classifica che fa sempre pi\u00f9 paura. E la panchina di Occhiuzzi inizia a scricchiolare<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>LECCE &#8211; Bisognava portare a casa con un risultato positivo per rimanere in scia di Reggina, Reggiana e Cremonese tutte vittoriose. Il Cosenza, invece,<strong>torna dalla trasferta di Lecce con zero punti<\/strong> e una gara che, ancora una volta, ha mostrato tutti i limiti preoccupanti di una squadra che era comunque riuscita a <strong>capitalizzare al massimo l&#8217;unica conclusione verso la porta di Gabriel<\/strong>, sbloccando al minuto 8&#8242; con il colpo di testa di Gliozzi, bravo a concretizzare l&#8217;assist perfetto di Petrucci. <strong>Vantaggio durato appena 3&#8242; minuti<\/strong> con il pareggio del Lecce che arriva su calcio di rigore trasformato da Coda, dopo un erroraccio di Legittimo costretto a falciare in area Rodriguez. Partita bruttina, ma assolutamente equilibrata anche perch\u00e8 il Cosenza, pur non riuscendo quasi mai a pungere, riesce a tenere a banda le velleit\u00e0 del Lecce che migliora nella ripresa con gli ingressi di Mancosu e Pettinari, ma deve ringraziare la topica clamorosa del direttore di gara che, a poco meno di 15&#8242; dal termine<strong>, concede un secondo calcio di rigore inesistente<\/strong> ai giallorossi per un presunto fallo di Sciaudone su Mancosu che poi va sul dischetto e realizza il 2 a 1. <strong>Il centrocampista colpisce nettamente la palla<\/strong> e non l&#8217;avversario. Il Cosenza crolla e 8&#8242; minuti dopo subisce anche il 3 a 1 con il <strong>colpo di testa di Meccariello<\/strong> che chiude la gara e spinge il Cosenza sempre pi\u00f9 gi\u00f9 cos\u00ec come il suo allenatore che inizia a sentire la sua panchina traballare.<\/p>\n<p>&nbsp;<\/p>\n<h4>Gliozzi inzuccata e goal, Coda pari su rigore<\/h4>\n<p>Nonostante le sollecitazioni e le critiche dopo le ultime prestazioni, Occhiuzzi resta fedele al suo modulo, ma cambia ancora una volta nelle scelte iniziali. In attacco torna Gliozzi che prende il posto di Carretta, mentre in difesa Ingrosso si riprende il posto da titolare. Esordio dal primo minuto per Crecco sulla corsia di sinistra. Pronti via e dopo appena 30&#8242; secondi,<strong> missile di Hjulmand e palla che si stampa sulla traversa<\/strong>. Rossoblu sorpresi dall&#8217;avvio di un Lecce subito arrembante che al 2&#8242; si rende ancora pericoloso con un<strong> colpo di testa di Bjorkengren<\/strong> bloccato da Falcone. Al 6&#8242; si vede anche il Cosenza con una girata di testa di Gliozzi che Gabriel devia in angolo. <strong>Passano due minuti e i rossoblu colpiscono<\/strong> proprio con un guizzo dello stesso attaccante di propriet\u00e0 del Monza. Gran cross di Petrucci dalla destra, Gliozzi si fionda sul pallone anticipando Meccariello e di testa, in tuffo, insacca sul primo palo. Ma la gioia del vantaggio dura appena 3&#8242; minuti. Legittimo si perde in area Rodriguez e nel disperato tentativo di evitare la conclusione dell&#8217;attaccante spagnolo, lo stende goffamente in area. <strong>Calcio di rigore che Coda realizza spiazzando Falcone<\/strong>. Partita che torna subito in equilibrio ma cala di ritmo. \u00c8 comunque un buon Cosenza. I rossoblu ribattono colpo su colpo non concedendo praticamente pi\u00f9 nulla al Lecce (fatta eccezione per una girata di testa larga di Coda). La squadra di Occhiuzzi gestisce bene il pallone provando anche a colpire, soprattutto con le giocate di Tremolada. Ma il primo tempo si chiude senza pi\u00f9 emozioni e con un tiro ciabattato di Petrucci sul fondo.<\/p>\n<h4>Un rigore inventato e Meccariello spengono il Cosenza<\/h4>\n<p>La ripresa si apre con gli stessi 22 della prima frazione e con il Cosenza che prova a pungere con la g<strong>irata di testa di Petrucci<\/strong>, imbeccato in area da Trotta, bloccata a terra da Gabriel. Il Lecce replica al 54&#8242; con una <strong>conclusione rasoterra di Majer<\/strong> che Falcone respinge con i piedi. La partita corre sul sottile filo dell&#8217;equilibrio, con le due squadre che combattono a centrocampo e folata offensive da una parte e dell&#8217;altra. Al 56&#8242; la palla giusta capita sui piedi di Coda liberato in area da Majer. <strong>Miracoloso l&#8217;intervento di Ingrosso<\/strong> in ripiegamento, che riesce a deviare la conclusione dell&#8217;attaccante. Il Lecce prova ad accelerare le giocate per trovare pertugi nella retroguardia del Cosenza che sembra andare in difficolt\u00e0 se presa in velocit\u00e0. Entrano Pettinari e Mancosu che<strong> al 66&#8242; spara in curva<\/strong> da ottima posizione. <strong>Occhiuzzi cambia due terzi dell&#8217;attacco<\/strong> inserendo Bahlouli e Carretta per Tremolada ed un opaco Trotta e poi butta nella mischia anche Mbakogu. Ma al 76&#8242; arriva la doccia fredda con il raddoppio del Lecce che suscita un vespaio di polemiche. Sciaudone, in ripiegamento sull&#8217;incursione in area di Mancosu, colpisce nettamente in pallone mandandolo in angolo. <strong>Per il signor Giua \u00e8 invece calcio di rigore<\/strong> tra che viene confermato nonostante le proteste veementi dei rossoblu. Sul dischetto lo stesso <strong>Mancosu trafigge Falcone<\/strong> che riesci solo a intuire la direzione. Un goal che spegne le speranze del Cosenza<strong> che al minuto 84&#8242; subisce anche il 3 a 1 con il colpo di testa di Meccariello<\/strong> che sottoporta corregge in rete l&#8217;assist di Maggio. Gara chiuse, Lecce che torna nelle zone altissime di classifica e Cosenza che affonda in classifica penalizzato da un regalo del direttore di gara.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><strong>US LECCE (4-3-1-2): <\/strong>Gabriel, Maggio, Lucioni, Meccariello, Gallo, Henderson (62&#8242; Mancosu), Hjulmand, Bjorkengren, Majer (81&#8242; Pisacane), Rodriguez, Coda (62&#8242; Pettinari)<strong><br \/>\nPanchina:<\/strong>Bleve, Vigorito, Pisacane, Paganini, Mancosu, Yalcin, Stepinski, Monterisi, Nikolov, Pettinari, Zuta, Maselli<br \/>\n<strong>Allenatore:<\/strong> Eugenio Corini<\/p>\n<p><strong>COSENZA CALCIO (3-4-1-2)<\/strong>: Falcone, Gerbo, Idda, Sciaudone (82&#8242; Sueva), Legittimo (82&#8242; Ba), Tremolada (66&#8242; Bahlouli), Gliozzi (74&#8242; Mbakogu), Crecco, Ingrosso, Trotta (66&#8242; Carretta), Petrucci<br \/>\n<strong>Panchina<\/strong>: Saracco, Corsi, Bahlouli, Mbakogu, Carretta, Sacko, Schiavi, Ba, Vera, Kone, Antzoulas, Suev<br \/>\n<strong>Allenatore<\/strong>: Roberto Occhiuzzi<\/p>\n<p><strong>Arbitro: <\/strong>Signor\u00a0Antonio Giua di Olbia<br \/>\n<strong>Assistenti:<\/strong> Signori Giuseppe Perrotti\u00a0di Campobasso e\u00a0Gamal Mokhtar\u00a0di Livorno<br \/>\n<strong>IV Uomo:<\/strong> Signor Giacomo Camplone\u00a0di Pescara<\/p>\n<p><strong>Ammoniti: <\/strong>Legittimo (C), Hjulmand (L), Coda (L), Ingrosso (C)<br \/>\n<strong>Espulsi:<\/strong><\/p>\n<p><strong>Angoli: <\/strong>2-4<br \/>\n<strong>Recupero: <\/strong>0&#8242; p.t. &#8211;<\/p>\n<p><strong>Note:<\/strong> Serata fresca a Lecce con una temperatura di 11 gradi. Terreno del Via del Mare in buone condizioni. Gara a porte chiuse per le disposizioni anti-Covid emanate dal Governo. Prima del fischio d&#8217;inizio le due squadre hanno osservato un minuto di silenzio in ricordo di Mauro Bellugi, ex calciatore di Inter, Bologna, Napoli e della Nazionale scomparso in settimana<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gara equilibrata sbloccata di testa da Gliozzi e pareggiata dopo 3&#8242; minuti dal rigore da Coda. Ma nel secondo tempo Giua assegna un secondo rigore inesistente al Lecce che chiude il match con il tris firmato da Meccariello. Per il Cosenza una sconfitta pesante con la classifica che fa sempre pi\u00f9 paura. E la panchina [&hellip;]<\/p>\n","protected":false},"author":23,"featured_media":145503,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-145502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=145502"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/145503"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=145502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=145502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=145502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}