{"id":145832,"date":"2021-02-27T15:10:55","date_gmt":"2021-02-27T14:10:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-cosenza-spezza-lincantesimo-marulla-battuto-il-chievo-e-primo-successo-interno\/"},"modified":"2023-01-16T17:28:34","modified_gmt":"2023-01-16T16:28:34","slug":"396387-il-cosenza-spezza-lincantesimo-marulla-battuto-il-chievo-e-primo-successo-interno","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/396387-il-cosenza-spezza-lincantesimo-marulla-battuto-il-chievo-e-primo-successo-interno\/","title":{"rendered":"Il Cosenza spezza l&#8217;incantesimo Marulla. Battuto il Chievo e primo successo interno"},"content":{"rendered":"<h4>Un autogoal di Renzetti al 10&#8242; del primo tempo permette al Cosenza di sfatare il tab\u00f9 Marulla e portare a casa un successo monumentale in ottica salvezza. Vani gli assalti del Chievo nella ripresa. I rossoblu resistono e possono festeggiare la prima vittoria interna<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211; Alla 25&#8242; giornata di campionato e a 8 mesi di distanza dall&#8217;ultima vittoria interna, <strong>il Cosenza torna finalmente ad assaporare il gusto dolce del successo al Marulla,<\/strong> grazie al successo per 1 a 0 contro il Chievo Verona, maturato al termine di un match combattuto e sofferto per la squadra di Mister Occhiuzzi che cambia modulo e salva la panchina dopo una settimana difficile. Il Cosenza parte subito forte e dopo aver sfiorato il vantaggio con Trotta,<strong> colpisce al 10&#8242; con un goal a met\u00e0 tra Gliozzi e il difensore del Chievo Renzetti,<\/strong> che sembra toccare per ultimo la sfera che finisce beffarda nella sua porta. I giallobli sono per\u00f2 squadra di rango <strong>e in almeno tre occasioni vanno vicino al pari<\/strong> con le conclusioni di Canotto, Ciciretti e Fabbro che trova sulla sua strada il solito ottimo Falcone. Anche il Cosenza ha la suo buona occasione con il <strong>sinistro a giro di Trotta che fa la barba al palo<\/strong>. Nel secondo tempo \u00e8 un&#8217;altra partita. Si gioca solo nella met\u00e0 campo dei rossoblu che chiudono tutti gli spazi e resistono agli attacchi del Chievo che a parte un paio di cross in area, si rende pericoloso solo nel finale con conclusioni dalla distanza. La pi\u00f9 pericolosa al 90&#8242; con <strong>un destro dai 25 metri dell&#8217;ex Garritano<\/strong> che Falcone devia in angolo. Il Cosenza invce spreca con Trotta in pieno recupero il goal del ko. Ma la vittoria arriva e i rossoblu incassano tre punti vitali in ottica salvezza.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/12378\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-396404\" src=\"https:\/\/quicosenza.it\/news\/12378\" alt=\"\" width=\"545\" height=\"304\" title=\"\"><\/a><\/p>\n<h4>Subito Cosenza e vantaggio al 10&#8242;, poi reazione Chievo<\/h4>\n<p>Era nell&#8217;aria da alcuni giorni. Occhiuzzi cambia modulo e schiera il Cosenza con il 4 3 1 2 affidando le corsia laterali Corsi e Legittimo e le chiavi del centrocampo a Gerbo con Petrucci e Leggimo ai lati. Tridente formato da Tremolada alle spalle di Gliozzi e Trotta. E il Cosenza parte subito bene rendendosi pericoloso al 2&#8242; con <strong>la sventola di Sciaudone dal limite<\/strong> che sibila alla destra di Semper. Il Chievo replica con l&#8217;incursione d Canotto e la <strong>conclusione di De Luca<\/strong> dalla destra respinta da Falcone. Ma il Cosenza \u00e8 pi\u00f9 determinato e <strong>al 10&#8242; trova il goal del vantaggio. <\/strong>Punizione in area di Corsi dalla destra, Gliozzi riesce a intervenire sulla palla ma \u00e8 la <strong>deviazione accidentale di Renzetti<\/strong> a spingerla nel sacco.\u00a0 Il Chievo \u00e8 squadra assai temibile e due minuti per poco non trova il pari con la <strong>conclusione di Ciciretti<\/strong> che sfrutta un buco della difesa rossoblu ma conclude centrale tra le braccia do Falcone. Minuto 20&#8242; e <strong>gran conclusione a giro di Trotta,<\/strong> da posizione impossibile, che esce di un nulla. La replica dei veneti \u00e8 nella girata di De Luca che si spegne sul fondo. La gara resta assolutamente gradevole e giocata su buoni ritmi con azioni ad una parte e dell&#8217;altra. Al 26&#8242; ripartenza dei rossoblu, <strong>Tremolada premia l&#8217;inserimento in area di Sciaudone<\/strong> che arriva con un attimo di ritardo e con riesce a colpire con forza. Molto pi\u00f9 pericolosa la <strong>conclusione di Canotto<\/strong> che calcia in diagonale da posizione difficile, con il pallone che esce di nulla. Alla mezz&#8217;ora ci vuole invece un<strong> grande intervento di Falcone<\/strong> per deviare in angolo la conclusione a botta sicura di Fabbro che al 24&#8242; ci prova anche di testa senza inquadrare la porta. \u00c8 il massimo sforzo del Chievo per cercare di recuperare lo svantaggio. Rossoblu a difesa del vantaggio che rischiano ancora al 44&#8242; con il rasoterra del solito Fabbro bloccato a terra da Falcone.<\/p>\n<h4>Secondo tempo<\/h4>\n<p>Ripresa con gli stessi 22 della prima frazione e con il Chievo riversato in avanti alla ricerca del pari. Il Cosenza serra le fila chiudendo tutti i varchi ai veneti, che allora provano a creare pericoli scodellando palloni in area e tentando con conclusioni dalla distanza. <strong>Al 62&#8242; Mogos lascia partite un diagonale dal limite<\/strong> che termina sul fondo. Brividi al 65&#8242; per la<strong>\u00a0sventola al volo<\/strong> del neo entrato Margiotta che si perde di poco alla sinistra di Falcone. Gerbo accusa un fastidio al polpaccio e viene sostituito da Crecco. Occhiuzzi si copre e sostituisce Gliozzi per Tiritiello. Cosenza a 5 dietro anche perch\u00e8 il Chievo butta nella mischia sia Di Gaudio che Margiotta. I rossoblu lottano su tutti i palloni e stringono le maglie della difesa, con il Chievo a girare palla da una parte e dell&#8217;altra del fronte offensivo per cercare spazi. Al minuto 87&#8242; <strong>Margiotta schiaccia di testa<\/strong> un cross dalla destra ma Falcone fa buona guardia. Occhiuzzi si sbraccia dalla panchina chiedendo il massimo sforzo ai suoi ragazzi che al 90&#8242;, in contropiede, sfiorano il raddoppio con la<strong> conclusione di Carretta<\/strong> che finisce sul fondo. Capovolgimento di fronte e gran tiro dell&#8217;ex Garritano dal limite che Falcone devia in angolo con un tuffo alla sula destra. Ma \u00e8 l&#8217;utimo pericolo per la pora dei rossoblu che conducono in porto il primo fondamentale successo interno della stagione,<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8211;<\/p>\n<p><strong>COSENZA CALCIO (4-3-1-2)<\/strong>: Falcone, Corsi, Gerbo (65&#8242; Crecco), Idda, Sciaudone (80&#8242; Ba), Legittimo, Tremolada (80&#8242; Carretta), Gliozzi (69&#8242; Tiritiello), Ingrossso, Trotta (80&#8242; Mbakogu), Petrucci<br \/>\n<strong>Panchina<\/strong>: Saracco, Tiritiello, Bahlouli, Mbakogu, Carretta, Sacko, Schiavi, Ba, Vera, Kone, Crecco, Sueva<br \/>\n<strong>Allenatore<\/strong>: Roberto Occhiuzzi<\/p>\n<p><strong>AC CHIEVO VERONA (4-4-2): <\/strong>Semper, Rigione, Leverbe, Fabbro, Obi (81&#8242; Bertagnoli), Renzetti, Palmiero (69&#8242; Viviani), Canotto (70&#8242; Di Gaudio), Mogos, De Luca (59&#8242; Margiotta), Ciciretti (59&#8242; Garritano)<strong><br \/>\nPanchina: <\/strong>Seculin, Bragantini, Zuelli, Di Gaudio, Vaisanen, Garritano, Pavlev, Viviani, Bertagnoli, Cotali, Prioire, Margiotta<br \/>\n<strong>Allenatore:<\/strong> Stefano Aglietti<\/p>\n<p><strong>Arbitro: <\/strong>Signor Maurizio Mariani di Aprilia<br \/>\n<strong>Assistenti:<\/strong> Signor Matteo Passeri di Gubbio e Damiano Di Iorio di Verbano Cusio Ossola<br \/>\n<strong>IV Uomo:<\/strong> Signor Matteo Marchetti di Ostia Lido<\/p>\n<p><strong>Ammoniti: <\/strong>Corsi (CS), Sciaudone (CS)<br \/>\n<strong>Espulsi:<\/strong><\/p>\n<p><strong>Angoli: <\/strong>1-4<br \/>\n<strong>Recupero:<\/strong> 1&#8242; p.t. &#8211; 5&#8242; s.t.<\/p>\n<p><strong>Note:<\/strong> Pomeriggio quasi primaverile a Cosenza con una temperatura di 22 gradi. Terreno del Marulla in perfette condizioni e gara che si disputa a porte chiuse per le disposizioni anti-covid<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un autogoal di Renzetti al 10&#8242; del primo tempo permette al Cosenza di sfatare il tab\u00f9 Marulla e portare a casa un successo monumentale in ottica salvezza. Vani gli assalti del Chievo nella ripresa. I rossoblu resistono e possono festeggiare la prima vittoria interna<\/p>\n","protected":false},"author":23,"featured_media":145833,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[],"class_list":["post-145832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=145832"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/145832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/145833"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=145832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=145832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=145832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}