{"id":146098,"date":"2021-03-04T15:40:05","date_gmt":"2021-03-04T14:40:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rifiuti-a-rende-bonificate-le-isole-ecologiche-il-monito-multe-ai-trasgressori\/"},"modified":"2023-01-16T17:28:51","modified_gmt":"2023-01-16T16:28:51","slug":"397156-rifiuti-a-rende-bonificate-le-isole-ecologiche-il-monito-multe-ai-trasgressori","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/397156-rifiuti-a-rende-bonificate-le-isole-ecologiche-il-monito-multe-ai-trasgressori\/","title":{"rendered":"Rifiuti a Rende, bonificate le isole ecologiche. Il monito: &#8220;multe ai trasgressori&#8221;"},"content":{"rendered":"<h4 dir=\"auto\">La task force di Calabria Maceri in azione questa mattina e la promessa di &#8220;sistemi di telecontrollo h24 finalizzati a monitore gli abbandoni illeciti&#8221;<\/h4>\n<p><!--more--><\/p>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">RENDE (CS) &#8211; A <strong>Rende,<\/strong> questa mattina, una taskforce di Calabria Maceri Spa &#8211; che si occupa della raccolta rifiuti &#8211; ha b<strong>onificato, sanificato e igienizzato le PEZ<\/strong> ( Postazione Ecologica Zonale) situate sul territorio. Lo fa sapere l&#8217;azienda che informa di aver agito &#8220;prima di<strong> attivare per le stesse sistemi di telecontrollo, finalizzati a monitorare abbandoni illeciti di rifiuti<\/strong> all&#8217;interno ed all&#8217;esterno delle <strong>PEZ, H24<\/strong>&#8220;.<\/div>\n<div dir=\"auto\"><\/div>\n<h4 dir=\"auto\">Pez, multe ai trasgressori<\/h4>\n<div dir=\"auto\">&#8220;Uno sforzo congiunto tra personale comunale, Rende Servizi e Calabra Maceri per restituire alla citt\u00e0, le PEZ <strong>da utilizzare, solo ed esclusivamente, in casi di necessit\u00e0<\/strong>.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">&#8220;Vi ricordiamo infatti, che nella citt\u00e0 di Rende, il conferimento dei rifiuti &#8211; concludono &#8211; deve avvenire secondo la <strong>modalit\u00e0 del porta a porta e che le PEZ non sostituiscono il porta a porta<\/strong>. I <strong>trasgressori saranno severamente puniti<\/strong> secondo le vigenti normative&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>La task force di Calabria Maceri in azione questa mattina e la promessa di &#8220;sistemi di telecontrollo h24 finalizzati a monitore gli abbandoni illeciti&#8221;<\/p>\n","protected":false},"author":58,"featured_media":146099,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-146098","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146098","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146098"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146098\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146099"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146098"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146098"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146098"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}