{"id":146430,"date":"2021-03-11T11:47:17","date_gmt":"2021-03-11T10:47:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/posti-letto-covid-in-meno-allannunziata-per-ora-bastano\/"},"modified":"2023-01-16T17:29:14","modified_gmt":"2023-01-16T16:29:14","slug":"398073-posti-letto-covid-in-meno-allannunziata-per-ora-bastano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/398073-posti-letto-covid-in-meno-allannunziata-per-ora-bastano\/","title":{"rendered":"Posti letto Covid in meno all&#8217;Annunziata, per ora bastano"},"content":{"rendered":"<h4>Nel periodo caldo della pandemia i posti letto dedicati a pazienti Covid erano 112. Ne sono stati dismessi 44<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Sono attualmente <strong>68<\/strong> i posti riservati a pazienti positivi al Covid 19 attivati dall\u2019azienda ospedaliera di Cosenza. Di questi, fino a ieri, 49 risultano occupati e pertanto 19 restano ancora liberi. La decisione di dismettere i posti Covid \u00e8 stata assunta dalla direzione dell&#8217;Azienda ospedaliera in virt\u00f9 del minore numero di accessi in ospedale di pazienti positivi e conseguentemente ripristinare le attivit\u00e0 ordinarie dei ricoveri all&#8217;Annunziata.<\/p>\n<p>Per quanto riguarda la suddivisione dei posti letto destinati ai pazienti colpiti dal virus, e che richiedono un&#8217;assistenza sanitaria specifica, 17 sono attivi e tutti occupati nel reparto di malattie infettive. Sono 18 le degenze attive nel reparto di pneumologia (17 i posti letto occupati), 19 in terapia intensiva (con 11 pazienti attualmente ricoverati) e 14 nel presidio di Rogliano dei quali 4 occupati.<\/p>\n<p>Secondo quanto riferito dalla Direzione dell&#8217;AO dalla fase emergenziale ad oggi sono stati dismessi 44 posti, riconvertiti per le attivit\u00e0 di routine dell\u2019ospedale, ma sono pronti a ritornare di esclusiva gestione covid se la situazione degli accessi in ospedale dovesse ritornare a salire.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nel periodo caldo della pandemia i posti letto dedicati a pazienti Covid erano 112. Ne sono stati dismessi 44<\/p>\n","protected":false},"author":42,"featured_media":146431,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[681],"class_list":["post-146430","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-coronavirus"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146430","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146430"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146430\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146431"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146430"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146430"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146430"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}