{"id":146488,"date":"2021-03-12T10:23:40","date_gmt":"2021-03-12T09:23:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/arrestato-in-spagna-il-pericoloso-latitante-di-san-luca-giuseppe-romeo\/"},"modified":"2023-01-16T17:29:17","modified_gmt":"2023-01-16T16:29:17","slug":"398234-arrestato-in-spagna-il-pericoloso-latitante-di-san-luca-giuseppe-romeo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/398234-arrestato-in-spagna-il-pericoloso-latitante-di-san-luca-giuseppe-romeo\/","title":{"rendered":"Arrestato in Spagna il pericoloso latitante di San Luca, Giuseppe Romeo"},"content":{"rendered":"<h4>La Guardia Civil spagnola lo ha scovato grazie ad una operazione di polizia resa possibile dalla cooperazione fornita dalla squadra mobile di Reggio Calabria e dallo Sco della Polizia di Stato<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN LUCA (RC) &#8211; Il suo arresto secondo gli inquirenti rappresenta un <strong>momento di particolare rilievo nell&#8217;attivit\u00e0 di contrasto al narcotraffico internazionale gestito dalla &#8216;ndrangheta.<\/strong> Il latitante Giuseppe Romeo \u00e8 stato arrestato nella serata di ieri in Spagna. Nel 2018 era sfuggito all&#8217;arresto nell&#8217;ambito dell&#8217;operazione antidroga &#8220;<strong>European &#8216;Ndrangheta Connection<\/strong>&#8220;, ed il gip all&#8217;epoca aveva emesso un mandato di arresto europeo. Negli ultimi giorni, le indagini hanno consentito alla Dda e alla polizia di Reggio di fornire ai colleghi spagnoli elementi significativi sulla sua presenza nella penisola iberica. Giuseppe Romeo era <strong>inserito nell&#8217;elenco dei latitanti pericolosi stilato dal ministero dell&#8217;Interno.<\/strong><\/p>\n<p>Conosciuto con i soprannomi &#8220;<strong>u pacciu&#8221;, &#8220;maluferru&#8221; o &#8220;u nanu&#8221;<\/strong>, il latitante \u00e8 figlio di Antonio Romeo, alias &#8220;<strong>centocapelli<\/strong>&#8220;, detenuto a Parma e ritenuto contiguo all&#8217;omonima cosca conosciuta con il nome di &#8220;Stacchi&#8221; di San Luca. Nel gruppo mafioso dei &#8220;Pelle-Costadura-Romeo&#8221;, al centro dell&#8217;inchiesta &#8220;European &#8216;Ndrangheta Connection&#8221;, il latitante ricopriva il ruolo di promotore, organizzatore e finanziatore dei traffici di cocaina in Europa.<\/p>\n<p>Stando alle indagini, Romeo era residente in Germania, ma <strong>faceva la spola fra la Calabria, la Lombardia e l&#8217;Europa nord-occidentale<\/strong> al fine di <strong>stringere accordi con i fornitori dello stupefacente<\/strong> e con alcuni intermediari dimoranti in Belgio, Olanda e Germania. Secondo gli inquirenti, Romeo<strong> riusciva a far arrivare 40 chili di cocaina a settimana dall&#8217;Olanda a Milano,<\/strong> con la collaborazione di altri sodali calabresi, alcuni dei quali gi\u00e0 condannati in primo grado a parecchi anni di reclusione. Cos\u00ec come lo stesso Romeo condannato anche per aver intestato fittiziamente le proprie quote del bar-gelateria &#8220;Caf\u00e8 La Piazza&#8221; di Bruggen, oggi sequestrato, ad altri soggetti imputati nel processo &#8220;European &#8216;Ndrangheta Connection&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Guardia Civil spagnola lo ha scovato grazie ad una operazione di polizia resa possibile dalla cooperazione fornita dalla squadra mobile di Reggio Calabria e dallo Sco della Polizia di Stato<\/p>\n","protected":false},"author":42,"featured_media":146489,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,22],"tags":[],"class_list":["post-146488","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-dal-mondo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146488"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146488\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146489"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146488"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146488"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}