{"id":146620,"date":"2021-03-15T15:48:37","date_gmt":"2021-03-15T14:48:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/salgono-ancora-i-contagi-nel-cosentino-120-da-ieri-in-calabria-213-e-4-vittime\/"},"modified":"2023-01-16T17:29:28","modified_gmt":"2023-01-16T16:29:28","slug":"398740-salgono-ancora-i-contagi-nel-cosentino-120-da-ieri-in-calabria-213-e-4-vittime","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/398740-salgono-ancora-i-contagi-nel-cosentino-120-da-ieri-in-calabria-213-e-4-vittime\/","title":{"rendered":"Salgono ancora i contagi nel cosentino: +121 da ieri. in Calabria +213 e 4 vittime"},"content":{"rendered":"<p>COSENZA &#8211; <strong>In discesa i nuovi contagi da covid<\/strong> in Calabria, anche se in provincia di Cosenza la situazione rimane attenzionata. Si registrano, infatti, altri 121 nuovi casi e con i posti letto quasi tutti occupati, tanto che all&#8217;Annunziata <a href=\"https:\/\/quicosenza.it\/news\/12494\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>saranno attivati altri 12 posti<\/strong><\/a> nel reparto di terapia sub-intensiva. Situazione ricoveri che peggiora in tutta la Regione mentre scende il dato sulle vittime con 4 morti nelle ultime 24 ore. Sono <strong>+213 i nuovi positivi accertati oggi dal dipartimento salute (ieri erano stati +300<\/strong><strong>)<\/strong> con un numero in calo di tamponi analizzati, sia molecolari che antigenici: <strong>ne sono stati processati 1.822<\/strong>\u00a0(ieri erano stati <strong>2.400<\/strong>), che portano il totale dei test a 621.131. Con l\u2019incremento odierno, comprese le vittime e i guariti,<strong> la Calabria raggiunge i 41.398 casi totali <\/strong>da inizio pandemia. Il maggior numero di nuovi contagi \u00e8 stato accertato ancora una volta in<strong> provincia<\/strong> <strong>Cosenza<\/strong> <strong>dove si registrano +121 nuovi positivi, <\/strong>in aumento rispetto ai +116 di ieri. Segue la provincia di Reggio Calabria con +64 contagi rispetto a ieri. Nel vibonese l&#8217;incremento \u00e8 di +20, mentre sono +7 nel catanzarese e solo un nuovo caso nel crotonese<\/p>\n<h4>Quattro le vittime. Salgono ancora i positivi<\/h4>\n<p>Analizzando i dati e i numeri sul contagio in Calabria, compresi i residenti e le persone da fuori regione, continua a crescere il numero di persone attualmente positive: <strong>sono in totale 7.636 i casi attivi<\/strong> al momento, 79 in pi\u00f9 rispetto a ieri. <strong>Il numero dei guariti sale in totale a 33.026,<\/strong> con un incremento di 130\u00a0 persone in pi\u00f9. Rispetto a ieri scende il numero dei decessi con quattro<strong>\u00a0vittime registrate nelle ultime 24 ore<\/strong> che portano il totale a 736: due a Vibo Valentia, una a Cosenza e una a Reggio Calabria.<\/p>\n<h4>Leggero calo dei ricoveri<\/h4>\n<p>Dopo il calo di ieri torna a salire il numero dei posti letto occupati negli ospedali calabresi. <strong>Ad oggi sono 280 le persone<\/strong> ricoverate in totale nei nosocomi calabresi. Di queste, <strong>258 sono nei reparti di malattie infettive (+12)<\/strong> e <strong>28 in terapia intensiva (-2)<\/strong>. Infine <strong>sale a 7.350 il numero di persone in isolamento<\/strong> domiciliare, 69 in pi\u00f9 rispetto a ieri. Di questi, 50 sono persone residenti in altre regioni o stati esteri. Dall\u2019ultima rilevazione, le persone che si sono registrate sul portale della Regione Calabria per comunicare la loro presenza sul territorio regionale sono in totale 175.<\/p>\n<h4><span style=\"color: #0000ff;\">Territorialmente i casi positivi sono cos\u00ec distribuiti:<\/span><\/h4>\n<p><strong>Cosenza<br \/>\n<\/strong>3.196 (53 in reparto Azienda ospedaliera di Cosenza; 16 in reparto al presidio di Rossano;15 al presidio ospedaliero di Acri; 17 al presidio ospedaliero di Cetraro; 0 all&#8217;ospedale da Campo; 13 in terapia intensiva, 3.082 in isolamento domiciliare); CASI CHIUSI 8.972 (8.670 guariti, 302 deceduti)<\/p>\n<p><strong>Catanzaro<\/strong><br \/>\nCASI ATTIVI 1.880 (25 in reparto all\u2019Azienda ospedaliera di Catanzaro; 6 in reparto al presidio di Lamezia Terme; 4 in reparto all\u2019Azienda ospedaliera universitaria Mater Domini; 8 in terapia intensiva; 1.837 in isolamento domiciliare); CASI CHIUSI 3.951 (3.847 guariti, 104 deceduti)<\/p>\n<p><strong>Crotone<\/strong><br \/>\nCASI ATTIVI 485 (22 in reparto; 463 in isolamento domiciliare); CASI CHIUSI 2.757 (2.712 guariti, 45 deceduti)<\/p>\n<p><strong>Vibo Valentia<br \/>\n<\/strong>CASI ATTIVI 534 (15 ricoverati, 519 in isolamento domiciliare); CASI CHIUSI 3.405 (3.341 guariti, 64 deceduti)<\/p>\n<p><strong>Reggio Calabria<br \/>\n<\/strong>CASI ATTIVI 1.491 (74 in reparto all&#8217;Azienda ospedaliera di Reggio Calabria; 11 in reparto al presidio ospedaliero di Gioia Tauro; 7 in terapia intensiva; 1.399 in isolamento domiciliare); CASI CHIUSI 14.368 (14.147 guariti, 221 deceduti)<\/p>\n<p><strong>Altra Regione o stato ester<\/strong>o: CASI ATTIVI 50 (50 in isolamento domiciliare); CASI CHIUSI 309 (309 guariti)<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Scendono i nuovi contagi in Calabria  con circa 1.800 tamponi. Ancora in salita i nuovi casi nel cosentino e continuano a crescere i ricoveri<\/p>\n","protected":false},"author":55,"featured_media":146621,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,17],"tags":[19],"class_list":["post-146620","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146620"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146620\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146621"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146620"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146620"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146620"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}