{"id":146811,"date":"2021-03-18T13:50:34","date_gmt":"2021-03-18T12:50:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/e-tornato-linverno-freddo-artico-sulla-calabria-e-neve-sopra-i-500-metri\/"},"modified":"2023-01-16T17:29:40","modified_gmt":"2023-01-16T16:29:40","slug":"399308-e-tornato-linverno-freddo-artico-sulla-calabria-e-neve-sopra-i-500-metri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/399308-e-tornato-linverno-freddo-artico-sulla-calabria-e-neve-sopra-i-500-metri\/","title":{"rendered":"\u00c8 tornato l&#8217;inverno. Freddo artico sulla Calabria e neve sopra i 500 metri"},"content":{"rendered":"<p>COSENZA <strong>&#8211; Buona parte della Calabria \u00e8 interessata da un\u2019ondata di freddo di origine artica <\/strong>che oramai ci sta interessando da inizio settimana e che continua ad affluire da nord est e che ha come obiettivo principalmente l&#8217;Est Europa ma anche buona parte del Mediterraneo, dove le correnti gelide scorrono lungo il bordo orientale dell&#8217;anticiclone. Nei giorni scorsi si \u00e8 creata una diffusa instabilit\u00e0 e sono tornate <strong>condizioni da pieno inverno con la neve caduta sui rilievi di Sila e Pollino<\/strong>. Nella notte, invece, si \u00e8 formato un blando vortice depressionario che sta portando un <strong>moderato peggioramento delle condizioni meteo<\/strong>. La neve ha iniziato ad imbiancare le alture del cosentino dalla tarda mattinata, con quota neve assestata sui 700\/800 metri. Poi, con il calo della temperatura, <strong>la quota neve si \u00e8 abbassata, scendendo intorno ai 500 metri.<\/strong><\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/12519\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter  wp-image-399332\" src=\"https:\/\/quicosenza.it\/news\/12519\" alt=\"\" width=\"573\" height=\"354\" title=\"\"><\/a><\/p>\n<p>Nel pomeriggio sono attese ancora condizioni di moderato maltempo sia sul versante ionico che si quello tirrenico, con quota neve in possibile ulteriore calo sull&#8217;alta Calabria fino ai 300\/400 metri di quota. <strong>Andr\u00e0 meglio domani quando il flusso artico assumer\u00e0 una traiettoria pi\u00f9 occidentale<\/strong>, richiamando sulla Calabria correnti pi\u00f9 miti che faranno rialzare le temperature di qualche grado. Per quanto riguarda il fine settimana cambier\u00e0 poco, mentre da luned\u00ec \u00e8 prevista una nuova irruzione di aria fredda con una forte ondata di maltempo che si abbatter\u00e0 per diversi giorni sul Sud Italia, portando nuovamente piogge intense e neve sulle quote medie (600\/700 metri).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;afflusso di correnti fredde artiche e un minimo di bassa pressione hanno creato condizioni di maltempo con pioggia neve nel cosentino sopra i 500 metri<\/p>\n","protected":false},"author":23,"featured_media":146812,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19,135],"class_list":["post-146811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146811"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146811\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146812"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}