{"id":146824,"date":"2021-03-18T16:10:29","date_gmt":"2021-03-18T15:10:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/le-vaccinazioni-di-astrazeneca-possono-riprendere-via-libera-dellema-e-sicuro-ed-efficace\/"},"modified":"2023-01-16T17:29:41","modified_gmt":"2023-01-16T16:29:41","slug":"399355-le-vaccinazioni-di-astrazeneca-possono-riprendere-via-libera-dellema-e-sicuro-ed-efficace","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/399355-le-vaccinazioni-di-astrazeneca-possono-riprendere-via-libera-dellema-e-sicuro-ed-efficace\/","title":{"rendered":"Le vaccinazioni di AstraZeneca possono riprendere. L&#8217;Ema &#8220;\u00e8 sicuro ed efficace&#8221;"},"content":{"rendered":"<p>\u00c8 arrivato<strong> il parere dell&#8217;Ema che ha dato il via libera a riprendere le immunizzazioni utilizzando le dosi del vaccino AtraZeneca<\/strong>. Il comitato sicurezza dell&#8217;agenzia europea del farmaco si era riunito per analizzare i dati dopo lo stop alle somministrazioni in alcune nazioni europee (compresa l&#8217;Italia) a causa di alcuni <strong>eventi avversi e di presunti casi di trombosi.<\/strong> Nella conferenza stampa \u00e8 stato dato il via libera da parte degli esperti perch\u00e9\u00a0 <strong>&#8220;il vaccino AstraZeneca \u00e8 sicuro, efficace, i benefici sono superiori ai rischi<\/strong> e<strong>d escludiamo relazioni tra casi di trombosi<\/strong>&#8221; ha affermato la direttrice di Ema Emer Cooke argomentando il via libera al vaccino evidenziando che comunque saranno effettuati &#8220;ulteriori approfondimenti per capire di pi\u00f9 riguardo gli eventi avversi rari segnalati dopo la vaccinazione&#8221;. Ieri anche l&#8217;Oms raccomanda l&#8217;uso del vaccino anglo-svedese ai Paesi che avevano sospeso le somministrazioni.<\/p>\n<p>Nelle motivazioni con cui Ema ha garantito la sicurezza del siero \u00e8 evidenziato che\u00a0&#8220;<strong>i casi di trombosi dopo la somministrazione del vaccino AstraZeneca sono inferiori a quelli che avvengono tra la popolazione non vaccinata. in totale <\/strong>25 casi avversi su 20 milioni di vaccinati&#8221; ha detto Sabien Straus, presidente del Prac (Commissione di farmacovigilanza) che ha poi aggiunto &#8220;<strong>il foglietto illustrativo del vaccino AstraZeneca &#8220;deve essere aggiornato<\/strong>: \u00e8 importante che venga comunicato al pubblico e agli operatori sanitari perch\u00e9 apprendano meglio queste informazioni, permettendo loro di mitigare questi effetti collaterali. &#8220;Vogliamo inviare una lettera ad AstraZeneca, che ci permette di avviare un dialogo con l&#8217;azienda nel quadro della risoluzione dei conflitti, la lettera \u00e8 in preparazione&#8221;: lo ha detto un portavoce della Commissione Ue, precisando che la lettera \u00e8 in preparazione, e che Bruxelles sta consultando gli Stati membri per poterla inviare rapidamente.<\/p>\n<h4>Draghi &#8220;le vaccinazioni riprendono domani&#8221;<\/h4>\n<p>Il governo italiano accoglie con soddisfazione il pronunciamento dell&#8217;Ema sul vaccino di AstraZeneca. La priorit\u00e0 del Governo rimane quella di realizzare il maggior numero di vaccinazioni nel pi\u00f9 breve tempo possibile&#8221;. Lo dice il premier Mario Draghi. D<strong>omani dalle ore 15.00 riprendono le vaccinazioni con il vaccino anti-Covid di AstraZeneca<\/strong>, comunica il ministero della Salute.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Via libera dell&#8217;Ema &#8220;il vaccino AstraZeneca \u00e8 sicuro, efficace, Rilevati solo 25 casi avversi su 20 milioni di vaccinati&#8221;<\/p>\n","protected":false},"author":55,"featured_media":146825,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-146824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146824"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146825"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}