{"id":146858,"date":"2021-03-19T10:01:47","date_gmt":"2021-03-19T09:01:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/parco-eolico-mongrassano-trasmesso-al-wwf-il-rapporto-fonometrico-sul-rumore\/"},"modified":"2023-01-16T17:29:44","modified_gmt":"2023-01-16T16:29:44","slug":"399447-parco-eolico-mongrassano-trasmesso-al-wwf-il-rapporto-fonometrico-sul-rumore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/399447-parco-eolico-mongrassano-trasmesso-al-wwf-il-rapporto-fonometrico-sul-rumore\/","title":{"rendered":"Parco eolico Mongrassano: &#8220;il livello sonoro non pu\u00f2 ritenersi accettabile&#8221;"},"content":{"rendered":"<p>MONGRASSANO (CS) &#8211; La richiesta di accesso ai dati ambientali \u00e8 stata trasmessa dal Dipartimento provinciale di Cosenza dell\u2019Arpacal, attraverso il servizio Radiazioni e Rumore diretto dall\u2019ing. Francesca Tarsia, alla locale sezione \u201cCalabria Citra\u201d del WWF di Fagnano Castello. Si tratta della documentazione relativa al rapporto fonometrico che l\u2019Arpacal ha svolto nel Comune di Mongrassano, e pi\u00f9 precisamente in localit\u00e0 \u201cAia dei Venti\u201d, dove opera un impianto eolico che la cittadinanza aveva diverse volte imputato come <strong>fattore di inquinamento acustico assolutamente insopportabile.<\/strong><\/p>\n<p>\u201cUn lavoro complesso e dettagliato \u2013 fanno sapere dal dipartimento cosentino dell\u2019Arpacal &#8211; realizzato dopo una interlocuzione con la ditta che ha installato l&#8217;impianto eolico, giungendo a conclusioni tecniche incontrovertibili. Dispiace che, in periodi passati il silenzio dell\u2019agenzia sia stato frainteso in una mancata collaborazione nei confronti della cittadinanza, ma \u00e8 stata prima rispettata una stringente normativa. Oggi, solo grazie alla liberatoria che ha concesso il Comune di Mongrassano, si rende pubblica l\u2019attivit\u00e0 svolta\u201d.<\/p>\n<p>La <strong>vicenda, risalente al maggio dello scorso anno<\/strong>, \u00e8 stata <strong>complessa da gestire<\/strong> perch\u00e9 a fronte della richiesta del sindaco di Mongrassano e dei cittadini di un intervento di misurazione tecnica del rumore prodotto dall\u2019impianto eolico \u00e8 stato necessario giungere, solo dopo apposito tavolo tecnico con la ditta proprietaria dell\u2019impianto, all\u2019inizio delle attivit\u00e0 di misurazione in campo a cura del Servizio radiazioni e Rumore del Dipartimento provinciale di Cosenza. Sono state necessarie <strong>ulteriori riunioni<\/strong>, nel corso delle quali la ditta proprietaria dell\u2019impianto, disponibile a fornire il supporto necessario all\u2019effettuazione delle misure, ha fatto presente che durante il mese di luglio 2020 ci sarebbe stata l\u2019opportunit\u00e0 di effettuare delle misurazioni in concomitanza di un \u201cprotocollo di on\/off\u201d, che avrebbe permesso le misurazioni con il funzionamento e lo spegnimento dell\u2019intero parco eolico.<\/p>\n<p>A seguito di questa ulteriore informazione si \u00e8 deciso di <strong>procedere con un monitoraggio in continuo<\/strong>, effettuato nei mesi di <strong>luglio e agosto<\/strong>, in almeno due postazioni di quelle ritenute pi\u00f9 sensibili ed esposte al rumore in questione. Le postazioni sono state identificate e scelte tra quelle facenti parte delle segnalazioni pervenute al Sindaco da parte della popolazione del Comune di Mongrassano.<strong> Con le misurazioni fonometriche<\/strong> sono stati acquisiti dati per circa 1500 ore totali, che con un tempo di acquisizione di 100ms (10 campioni al secondo), con una mole totale di dati di oltre <strong>50 milioni di campioni da analizzare<\/strong>, ciascuno corredato del proprio spettro acustico.<\/p>\n<p>\u201cIn ambiente abitativo \u2013 \u00e8 scritto nel rapporto tecnico di Arpacal a firma dei tecnici Ing. Nicola Miglino e Dr. Emilio Pellicori &#8211;<strong> il livello sonoro<\/strong> prodotto dal funzionamento del parco eolico \u201cAria del Vento\u201d, sito in localit\u00e0 Aia dei Venti nel Comune di Mongrassano, <strong>non pu\u00f2 ritenersi accettabile<\/strong>, in quanto sono stati registrati, ad infissi aperti all\u2019interno dell\u2019ambiente abitativo individuato dalla postazione 1, valori superiori ai limiti di legge, come descritto al punto 4) del presente rapporto\u201d.<\/p>\n<p>Occorre ricordare, infine, che il rapporto era stato regolarmente trasmesso al Comune di Mongrassano nell\u2019ottobre dello scorso anno, ed a fronte di una richiesta di accesso l\u2019Agenzia non aveva potuto procedere a consegnare la documentazione, perch\u00e9 non aveva ricevuto la liberatoria del Comune stesso, in qualit\u00e0 di titolare del procedimento autorizzatorio dell\u2019impianto. Su nuova richiesta del WWF, ed ottenendo la liberatoria prevista dalla normativa, l\u2019Agenzia ha potuto quindi evadere la richiesta di accesso ai dati ambientali e quindi condividere questo rapporto con l\u2019opinione pubblica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Dipartimento provinciale di Cosenza dell\u2019Arpacal, ha trasmesso alla locale sezione \u201cCalabria Citra\u201d del WWF di Fagnano Castello, la documentazione relativa al rapporto fonometrico svolto<\/p>\n","protected":false},"author":42,"featured_media":146859,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-146858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146858"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146858\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146859"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}