{"id":146976,"date":"2021-03-22T12:37:37","date_gmt":"2021-03-22T11:37:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/omicidio-a-mongrassano-travolge-il-fratello-con-lauto-e-scappa\/"},"modified":"2023-01-16T17:29:52","modified_gmt":"2023-01-16T16:29:52","slug":"399820-omicidio-a-mongrassano-travolge-il-fratello-con-lauto-e-scappa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/399820-omicidio-a-mongrassano-travolge-il-fratello-con-lauto-e-scappa\/","title":{"rendered":"Mongrassano, travolge e uccide il fratello con l&#8217;auto. Arrestato dopo una breve fuga"},"content":{"rendered":"<p>MONGRASSANO (CS) &#8211; \u00c8 <strong>accusato di omicidio volontario aggravat<\/strong>o, Giuseppe Marino, 43 anni, che nella tarda mattinata di oggi ha ucciso il proprio fratello, <strong>Pasquale di 45 anni, travolgendolo con l\u2019auto<\/strong>. Il fatto \u00e8 accaduto a <strong>Mongrassano<\/strong>, <strong>nei pressi del municipio<\/strong>.\u00a0Sul luogo dell&#8217;omicidio sono giunti gli uomini dell&#8217;Arma della Compagnia di San Marco Argentano, per i rilievi del caso. Secondo una prima ricostruzione dei fatti, l\u2019uomo era alla guida di un&#8217;auto di grossa cilindrata, una Bmw scura con targa straniera, quando ha investito il fratello, passando sul corpo pi\u00f9 volte, per poi sfrecciare via. L<strong>a vittima \u00e8 morta sul colpo, dilaniato dall\u2019impatto e dal peso dell\u2019auto che pi\u00f9 volte gli \u00e8 passata sopra.<\/strong> Ad assistere alla scena alcuni passanti che hanno allertato i carabinieri.<\/p>\n<p>La fuga di Giuseppe Marino, per\u00f2, \u00e8 durata solo qualche ora: l<strong>\u2019uomo \u00e8 stato rintracciato dai carabinieri della sezione Radiomobile di Cosenza, nella zona del tribunale,<\/strong> nel capoluogo bruzio, a bordo di un&#8217;auto diversa da quella utilizzata per compiere l&#8217;omicidio e con un&#8217;altra persona, la cui posizione \u00e8 al vaglio degli inquirenti. L&#8217;auto utilizzata per il delitto, invece, \u00e8 stata ritrovata in un secondo momento, non lontano dal luogo dell&#8217;omicidio, a<strong>bbandonata in mezzo al verde nei pressi della vecchia Cavallerizzo, frazione di Cerzeto<\/strong>, area interdetta dopo la frana del 2005. Sono in corso accertamenti tecnici sull&#8217;auto da parte dei militari specializzati del Comando provinciale di Cosenza.\u00a0Il quarantatreenne, secondo quanto si apprende, h<strong>a ammesso le proprie responsabilit\u00e0<\/strong> ed \u00e8 stat<strong>o sottoposto ad interrogatorio da parte dei magistrati inquirenti:<\/strong> il Pm Donatella Donato e il procuratore capo Mario Spagnuolo. Il movente sarebbe da rintracciare in continui litigi tra i due, che coinvolgerebbero anche la figlia del presunto assassino. In passato tra i due fratelli c&#8217;erano stati altri screzi e ripetuti liti, che sono terminati in denunce reciproche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La vittima, \u00e8 morta sul colpo. Ad assistere alla scena alcuni passanti che hanno allertato i carabinieri. L&#8217;uomo rintracciato a Cosenza<\/p>\n","protected":false},"author":56,"featured_media":146977,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-146976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=146976"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/146976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/146977"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=146976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=146976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=146976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}