{"id":147207,"date":"2021-03-26T05:37:25","date_gmt":"2021-03-26T04:37:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/paola-minacce-dal-carcere-al-procuratore-pierpaolo-bruni\/"},"modified":"2023-01-16T17:30:06","modified_gmt":"2023-01-16T16:30:06","slug":"400453-paola-minacce-dal-carcere-al-procuratore-pierpaolo-bruni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/400453-paola-minacce-dal-carcere-al-procuratore-pierpaolo-bruni\/","title":{"rendered":"Paola, minacce dal carcere al procuratore Pierpaolo Bruni"},"content":{"rendered":"<p>PAOLA (CS) &#8211; E&#8217; tutto contenuto in un audio e in alcune immagini che non lascerebbero dubbi all\u2019intenzione di \u201costacolare\u201d il procuratore di Paola, Pierpaolo Bruni. Parole ma anche gesti appartenenti ad un linguaggio non verbale estremamente chiaro, scambiato tra il <strong>detenuto e la moglie<\/strong>, che evidenzierebbero la volont\u00e0 di mettere in atto ritorsioni nei confronti del procuratore.<\/p>\n<p>L\u2019uomo deve scontare sei anni di carcere perch\u00e9 coinvolto in una precedente indagine della Dda condotta sempre dal procuratore Bruni quando si occupava del territorio crotonese e inoltre \u00e8 coinvolto nel procedimento scaturito dall\u2019inchiesta \u201c<strong>Tonno Rosso<\/strong>\u201d, che qualche giorni fa, ha fatto registrare tre condanne e un rinvio a giudizio.<\/p>\n<p>Solidariet\u00e0 al procuratore Bruni \u00e8 stata espressa dal senatore di Italia Viva, <strong>Ernesto Magorno<\/strong>: &#8220;Parole orrende da condannare. La Calabria che vale sta con gli operatori di legalit\u00e0&#8221;. Un messaggio di vicinanza anche da parte del vicepresidente della commissione regionale anti &#8216;ndrangheta, <strong>Graziano Di Natale<\/strong>: &#8220;Atto gravissimo. Bruni \u00e8 colonna portante nella lotta alla Ndrangheta. Non va lasciato solo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un detenuto nel carcere di Paola \u00e8 stato intercettato a colloquio con la moglie mentre esprime forme di risentimento nei confronti del Procuratore capo della Repubblica di Paola, Pierpaolo Bruni<\/p>\n","protected":false},"author":42,"featured_media":147208,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-147207","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=147207"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147207\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/147208"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=147207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=147207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=147207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}