{"id":147433,"date":"2021-03-30T10:45:49","date_gmt":"2021-03-30T08:45:49","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/fp-cgil-di-cosenza-vaccinare-gli-operatori-ecologici\/"},"modified":"2023-01-16T17:30:21","modified_gmt":"2023-01-16T16:30:21","slug":"401130-fp-cgil-di-cosenza-vaccinare-gli-operatori-ecologici","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/401130-fp-cgil-di-cosenza-vaccinare-gli-operatori-ecologici\/","title":{"rendered":"FP Cgil di Cosenza: &#8220;vaccinare gli operatori ecologici&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Bisogna fare presto&#8221; scrive il segretario FP Cgil di Cosenza Francesco Piro. &#8220;Gli operatori ecologici hanno continuato a pulire le nostre strade, a raccogliere i nostri rifiuti, casa per casa, svolgendo un servizio pubblico essenziale. Non sempre \u00e8 stato possibile svolgere il proprio lavoro proteggendosi. A volte completare il proprio turno ha significato rischiare la propria salute. Raccogliere, tra gli altri, i rifiuti di tutti i cittadini contagiati dal virus, ha inciso, profondamente, su una situazione spesso gi\u00e0 molto delicata&#8221;.<\/p>\n<p>&#8220;A questi lavoratori &#8211; scrive Piro &#8211; va tutto il nostro ringraziamento e quello di tutta la comunit\u00e0. In relazione alla <strong>richiesta urgente indirizzata dall&#8217;Asp di Cosenza<\/strong> di fornire gli elenchi dei lavoratori che svolgono servizi essenziali, si precisa che le aziende in questione dovranno ottemperare a quanto sollecitato, atteso che gli operatori ecologici rientrano nella suddetta categoria ed hanno, pertanto, diritto di aderire alla campagna vaccinale SARS Covid-19&#8243;.<\/p>\n<p>&#8220;Pertanto sollecitiamo tutte le aziende operanti nel settore dell\u2019igiene ambientale, a prendere contatti con l\u2019ASP e fornire gli elenchi di tutti i lavoratori interessati. La salute \u00e8 un diritto costituzionalmente tutelato, ragion per cui diventa obbligo morale garantire la sicurezza nei confronti di soggetti che continuano ad offrire i loro servizi alla comunit\u00e0 nonostante l\u2019eccezionalit\u00e0 del momento&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Non solo medici e infermieri, ci sono anche altri lavoratori che, in piena emergenza Coronavirus, hanno continuato a lavorare tutti i giorni&#8221;<\/p>\n","protected":false},"author":42,"featured_media":147434,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-147433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=147433"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147433\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/147434"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=147433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=147433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=147433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}