{"id":147647,"date":"2021-04-02T17:51:59","date_gmt":"2021-04-02T15:51:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/niente-vaccino-per-me-papa-di-una-bimba-cardiopatica\/"},"modified":"2023-01-16T17:30:35","modified_gmt":"2023-01-16T16:30:35","slug":"401728-niente-vaccino-per-me-papa-di-una-bimba-cardiopatica","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/401728-niente-vaccino-per-me-papa-di-una-bimba-cardiopatica\/","title":{"rendered":"&#8220;Niente vaccino per me, pap\u00e0 di una bimba cardiopatica&#8221;"},"content":{"rendered":"<div>MORANO CALABRO (CS) &#8211; &#8220;<strong>Sono il pap\u00e0 di una bambina di sei anni affetta da cardiopatia congenita grave<\/strong>. In base alla nuova nota, inserita di recente, dal Ministero della Salute, relativamente alle vaccinazioni Covid 19, negli elenchi dei <strong>soggetti fragili<\/strong> in fondo alla tabella 1, con asterisco si rende noto che: &#8216;possono essere vaccinati i conviventi&#8217;&#8230; nello specifico&#8217; in caso di minori che rientrano nella definizione di estremamente vulnerabili e che non possono essere vaccinati per mancanza di vaccini indicati per la loro fascia di et\u00e0, vaccinare i relativi genitori \/tutori\/affidatari &#8220;. Purtroppo per\u00f2 la <strong>Regione Calabria<\/strong>, dopo aver attivato il portale atto alla registrazione, di fatto, non permette a tali soggetti di prenotare alcun vaccino, perch\u00e9 non contemplati negli elenchi dei soggetti cosiddetti fragili. Sono giorni che provo a mettermi in contatto con tutti i numeri dell&#8217;URP della Regione ma nessuno risponde. Ritengo giusto e opportuno, anche per quanti si trovano nelle mie medesime condizioni, segnalare questa <strong>grave anomalia<\/strong>. Mi risulta che regioni come la Toscana e il Lazio abbiano gia\u0300 provveduto ad attivare una finestra sul portale della Regione per prenotarsi&#8230; noi invece veniamo come al solito ignorati.<\/div>\n<div><\/div>\n<div>Per quanto mi riguarda, non avendo potuto prenotare la vaccinazione mediante inserimento del mio codice fiscale e numero tessera sanitaria a mezzo piattaforma regionale, non potendo fare altrimenti, ho utilizzato i dati della minore fragile (mia figlia) per entrare nel sistema e ottenere la data della somministrazione del siero a mio favore. Cos\u00ec il giorno fissato automaticamente dall&#8217;applicazione telematica, 31 marzo 2021, mi sono recato alle ore 17.00 presso <strong>l&#8217;ospedale di Castrovillari<\/strong> e con mio grande stupore e rammarico, dopo aver atteso circa un&#8217;ora, mi \u00e8 stato comunicato da un operatore della Croce Rossa Italiana che non avrei potuto accedere alla profilassi a causa della discordanza tra le mie generalit\u00e0 e quelle della minore fragile, ovvero mia figlia. Al momento, nonostante i presupposti ex lege per l&#8217;accesso, mi ritrovo a non sapere se e quando sar\u00f2 sottoposto a vaccinazione&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Riceviamo e pubblichiamo la nota di un genitore di Morano Calabro, impossibilitato a effettuare la prenotazione sul portale della Regione<\/p>\n","protected":false},"author":21,"featured_media":147648,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-147647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=147647"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/147648"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=147647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=147647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=147647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}