{"id":147669,"date":"2021-04-03T11:17:11","date_gmt":"2021-04-03T09:17:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/covid-rossano-ambulanze-in-fila-nella-notte\/"},"modified":"2023-01-16T17:30:37","modified_gmt":"2023-01-16T16:30:37","slug":"401766-covid-rossano-ambulanze-in-fila-nella-notte","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/401766-covid-rossano-ambulanze-in-fila-nella-notte\/","title":{"rendered":"Covid: Rossano, ambulanze in fila nella notte"},"content":{"rendered":"<p>CORIGLIANO ROSSANO &#8211; Sei ambulanze con pazienti con sintomi da Covid 19 sono rimaste in fila per tutta la notte all&#8217;ospedale &#8220;Nicola Giannettasio&#8221; di Rossano. Al pronto soccorso, in attesa dell&#8217;ampliamento del reparto Covid gi\u00e0 esistente e saturo, agli otto pazienti da allocare in reparto si sono aggiunti ulteriori arrivi. Non sono mancati momenti di tensione tra i familiari e il personale medico prima di riuscire a trasferire alcuni pazienti in altri ospedali. Diverse, secondo quanto riferito, sono le difficolt\u00e0 dei medici del pronto soccorso che si ritrovano a dover effettuare diversi controlli medici per stabilire la positivit\u00e0 al Covid 19 dei pazienti. Per le altre emergenze di primo soccorso \u00e8 ormai operativo solo l&#8217;ospedale &#8220;Guido Compagna&#8221; di Corigliano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sei ambulanze con pazienti con sintomi da Covid 19 sono rimaste in attesa per ore<\/p>\n","protected":false},"author":56,"featured_media":147670,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[19],"class_list":["post-147669","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/56"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=147669"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147669\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/147670"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=147669"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=147669"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=147669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}