{"id":147806,"date":"2021-04-10T11:00:42","date_gmt":"2021-04-10T09:00:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/comune-di-rende-e-unical-firmano-convenzione-per-tirocini-formativi\/"},"modified":"2023-01-16T17:30:45","modified_gmt":"2023-01-16T16:30:45","slug":"402119-comune-di-rende-e-unical-firmano-convenzione-per-tirocini-formativi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/402119-comune-di-rende-e-unical-firmano-convenzione-per-tirocini-formativi\/","title":{"rendered":"Comune di Rende e Unical firmano convenzione per tirocini formativi"},"content":{"rendered":"<p>RENDE &#8211; E&#8217; stato approvato dalla giunta Manna lo schema di convenzione per i <strong>tirocini di formazione<\/strong> e <strong>orientamento curriculare<\/strong> tra il dipartimento di Studi Umanistici, il dipartimento di Culture, Educazione e Societ\u00e0, Corso di Studi in Gestione e Conservazione dei Documenti Digitali dell\u2019Universit\u00e0 della Calabria e il comune di Rende. &#8220;Siamo convinti che le eccellenze all\u2019interno del nostro ateneo &#8211; dichiara il sindaco Marcello Manna &#8211; debbano essere valorizzate e messe a disposizione dei nostri territori per uno sviluppo pi\u00f9 sostenibile\u201d.<\/p>\n<p>I tirocini, nello specifico: \u201csi vanno ad aggiungere al rinnovato accordo con il DiSu, giunto gi\u00e0 al quinto anno, che ci ha permesso di portare i docenti Unical a lezione nei nostri istituti d\u2019istruzione superiore con i laboratori di cittadinanza attiva. <strong>Promuovere spazi di confronto e riflessone su temi di attualit\u00e0 nei licei<\/strong> &#8211; ha affermato Manna \u2013 vuol dire <strong>10<\/strong> da parte delle giovani generazioni: per farlo \u00e8 fondamentale informare e sollecitare l\u2019attenzione degli studenti sull\u2019inclusione, la tolleranza, l\u2019uguaglianza. Solo cos\u00ec il processo democratico di partecipazione alla cosa pubblica pu\u00f2 realmente compiersi in un costante dialogo tra cittadini e istituzioni\u201d.<\/p>\n<p>Digitalizzazione e implementazione delle conoscenze acquisite nell\u2019ambito degli studi universitari tra gli obiettivi dei tirocini che gli studenti Unical potranno intraprendere all\u2019interno del municipio dell\u2019oltre Campagnano: \u201cl\u2019opportunit\u00e0 per i nostri giovani di trarre beneficio da tale rete \u00e8 evidente: consentire all\u2019Universit\u00e0 di definire una didattica efficace e un apprendimento attivo e partecipato &#8211; spiega Manna &#8211; significa incrementare percorsi formativi e di studio che rispondano alle esigenze del tessuto produttivo del nostro territorio oltre a favorire l\u2019occupazione nelle aziende locali le quali, a loro volta, potrebbero avere la possibilit\u00e0 di impiegare personale sempre pi\u00f9 qualificato\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Si rafforza \u2013 dichiara il sindaco Manna &#8211; il rapporto tra i nostri enti che da anni collaborano su diversi piani d\u2019intervento in ambito non solo di istruzione e ricerca, ma anche di innovazione scientifica, culturale e ambientale&#8221;<\/p>\n","protected":false},"author":42,"featured_media":147807,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-147806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=147806"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/147806\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/147807"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=147806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=147806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=147806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}