{"id":148380,"date":"2021-04-17T14:03:04","date_gmt":"2021-04-17T12:03:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-e-la-resa-definitiva-i-rossoblu-crollano-anche-a-pisa-serie-c-a-un-passo\/"},"modified":"2023-01-16T17:31:24","modified_gmt":"2023-01-16T16:31:24","slug":"403761-cosenza-e-la-resa-definitiva-i-rossoblu-crollano-anche-a-pisa-serie-c-a-un-passo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/403761-cosenza-e-la-resa-definitiva-i-rossoblu-crollano-anche-a-pisa-serie-c-a-un-passo\/","title":{"rendered":"Cosenza, \u00e8 la resa definitiva. I rossoblu crollano anche a Pisa, Serie C a un passo"},"content":{"rendered":"<p>PISA &#8211; Era una vera e propria partita da ultima spiaggia quella dei rossoblu, reduci da una settimana pesantissima e chiamati al successo, o comunque al risultato positivo, per non veder scappare via l&#8217;Ascoli, vittorioso ieri sera a Ferrara, per provare quanto meno a rimanere incollati alla speranza di disputare i play-out. Ed invece <strong>la gara dell&#8217;Arena Garibaldi si trasforma nell&#8217;ennesima disfatta\u00a0<\/strong>per la sqaudra di Occhiuzzi,<strong> sconfitta nuovamente con un netto 3 a 0<\/strong>. I lupi <strong>rimediano la terza sconfitta consecutiva<\/strong> e scivolano sempre pi\u00f9 in fondo in classifica, a 5 punti dai marchigiani, raggiunti in classifica dalla Reggina e con le porte della Serie C oramai ad un passo considerando che la prossima gara (il match con il Pescara \u00e8 stato rinviato per covid) si giocher\u00e0 ad Empoli contro la prima in classifica. In questo momento il Cosenza sarebbe gi\u00e0 retrocesso in Serie C visto che hanno 5 punti di distacco dall&#8217;Ascoli.<\/p>\n<p>Dopo aver colpito una traversa con Sacko ed aver disputato un discreto primo tempo, il Cosenza \u00e8 letteralmente scomparso dal campo dopo aver subito in apertura di ripresa il <strong>vantaggio di Gucher, <\/strong>arrivato su un goffo errore difensivo. La rezione non c&#8217;\u00e8 e come a Venezia la sqaudra scompare letteralmente dal campo. A met\u00e0 secondo tempo arriva il <strong>raddoppio di Mazzitelli direttamente su punizione. <\/strong>Mentre Occhiuzzi cambia giocatori come fossero noccioline, il Pisa cala il tris con Marin a 3&#8242; dal termine e mette in archivio un successo tanto meritato quanto pesantissimo per un Cosenza sempre pi\u00f9 irriconoscibile e abbandonato al proprio destino.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/12730\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-403806\" src=\"https:\/\/quicosenza.it\/news\/12730\" alt=\"\" width=\"545\" height=\"343\" title=\"\"><\/a><\/p>\n<h4>Traversa di Sacko, Palombi si divora il vantaggio<\/h4>\n<p>Occhiuzzi, sulla graticola, prova il tutto per tutto cambiando 5 giocatori rispetto alla sconfitta di Venezia rispolverando Sacko in attacco, nel tridente con Carretta e Gliozzi. Pronti via e la prima occasione \u00e8 del Pisa, con una<strong> girata dal limite di Mazzitelli<\/strong> che spara in curva. Pisa ancora pericoloso con un <strong>colpo di tacco volante di Palombi<\/strong> sul primo palo che finisce fuori. Al 13&#8242;, per\u00f2, \u00e8 il<strong> Cosenza andare vicinissimo al vantaggio con Sacko.<\/strong> L&#8217;attaccante francese raccoglie un cross di Corsi in area e gira di testa, Gori con uno strepitoso intervento riesce a deviare la sfera che <strong>si stampa sulla traversa<\/strong>.\u00a0 Capovolgimento di fronte e <strong>conclusione di Vido nel cuore dell&#8217;area<\/strong> che non inquadra la porta. Due minuti dopo l&#8217;attaccante del Pisa scalda le mani a Falcone con un gran tiro dalla distanza. La partita \u00e8 gradevole con il Pisa a fare gioco e il Cosenza pronto a ripartire in contropiede.<strong> Al 28&#8242; l&#8217;occasione pi\u00f9 pericolosa per i padroni di casa<\/strong> con Palombi imbeccato in area da Vido. L&#8217;attaccante si presenta a tu per tu con Falcone ma chiude troppo l&#8217;interno e la palla si perde sul fondo. Sale il baricentro del Pisa ma i rossoblu si rendono pericolosi con un<strong> colpo di testa di Tiritello<\/strong> largo e un&#8217;azione personale al 43&#8242; di Carretta che, palla al piede, arriva alla conclusione murata da un miracoloso intervento di Caracciolo. \u00c8 l&#8217;ultima occasione di un primo tempo comunque equilibrato che si chiude senza reti.<\/p>\n<h4>Subito Guher, la chiudono Mazzitelli e Marin<\/h4>\n<p>La ripresa si apre subito in salita per i rossoblu, visto che<strong> dopo appena 4&#8242; minuti il Pisa trova il goal del\u00a0<\/strong><b>vantaggio<\/b>. Goffo intervento di Tiritiello, Gucher ne approfitta per prendere palla ed entrare in area, dove fa sedere con una finta Schiavi, e in diagonale batte Falcone che riesce solo a deviare la sfera che termina la sua corsa nell&#8217;angolo basso. Occhiuzzi toglie dal campo Shiavi, inserisce Tremolada schierando il Cosenza con un 4-3-2-1 nella speranza di aumentare il peso offensivo. Ma la mossa non sortisce gli effetti sperati anzi, i rossoblu cos\u00ec come avvenuto a Venezia, scompaiono dal campo e <strong>al 72&#8242; subiscono anche il goal del 2 a 0<\/strong>. Intervento maldestro della difesa su un fallo laterale per il Cosenza e Sciudone che commette un ingenuo quanto inutile fallo al limite dell&#8217;area. Mazzitelli si incarica della battuta e con un destro preciso, <strong>aggira la barriera, insacca nell&#8217;angolo basso con Falcone immobile<\/strong>. Una mazzata per il Cosenza e per Occhiuzzi che a una decina di minuti dal termine effettua una triplo cambio cambio della disperazione inserendo Sueva, Kone e Trotta. Ma i rossoblu sono gi\u00e0 negli spogliatoi e<strong> al minuto 84&#8242; Marin cala il tris<\/strong> battendo Falcone con un preciso diagonale, dopo una bella triangolazione con Belli. \u00c8 la resa definitiva di una squadra svuotata e totale in confusione.<\/p>\n<p>&nbsp;<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<\/p>\n<p><strong>AC PISA 1909 (4-3-1-2):<\/strong> Gori, Birindelli, Caracciolo, Palombi (56&#8242; Marconi), Meroni, Marin, Vido (67&#8242; Belli), Quaini (46&#8242; Siega), Gucher (87&#8242; Mastinu), Beghetto (67&#8242; Sibilli), Mazzitelli<br \/>\n<strong>Panchina:<\/strong> Perilli, Loria, Belli, Siega, Mastinu, Bechini, Sibilli, Lisi, Masetti, Marconi, Benedetti, Marsura<br \/>\n<strong>Allenatore:\u00a0<\/strong>Luca D&#8217;Angelo<\/p>\n<p><strong>COSENZA CALCIO (3-4-1-2)<\/strong>: Falcone, Corsi, Tiritiello, Carretta, Sacko (78&#8242; Sueva), Schiavi (60&#8242; Tremolada), Sciaudone (78&#8242; Kone), Ba, Gliozzi (78&#8242; Trotta), Crecco, Ingrosso<br \/>\n<strong>Panchina:\u00a0<\/strong>Saracco, Matosevic, Idda, Bahlouoli, Bouah, Vera, Tremolada, Kone, Trotta, Antzoulas, Sueva<br \/>\n<strong>Allenatore:<\/strong> Roberto Occhiuzzi<\/p>\n<p><strong>Arbitro:\u00a0<\/strong>Signor \u00a0Rosario Abisso di Palermo<br \/>\n<strong>Assistenti:<\/strong> Signor\u00a0Enrico Caliari di Legnago e Signor Michele Grossi\u00a0di Frosinone<br \/>\n<strong>IV Uomo:<\/strong> Signor Manuel Volpi di Arezzo<\/p>\n<p><strong>Ammoniti: <\/strong>Quaini (P), Ba (C), Sciaudone (C), Biridelli (P)<br \/>\n<strong>Espulsi:<\/strong><\/p>\n<p><strong>Angoli: <\/strong>3-5<br \/>\n<strong>Recupero: <\/strong>2&#8242; p.t. &#8211; 3&#8242; s.t.<\/p>\n<p><strong>Note:<\/strong> Pomeriggio soleggiato a Pisa con una temperatura di circa 18 gradi. Terreno dell&#8217;Arena Garibaldi in buone condizioni, gara a porte chiuse per le disposizioni anti-covid<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I rossoblu crollano nuovamente e subiscono un altro pesante 3 a 0. La sqaudra ha messo di lottare prigioniera al proprio destino<\/p>\n","protected":false},"author":23,"featured_media":148381,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[20],"tags":[19],"class_list":["post-148380","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sport","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/148380","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/23"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=148380"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/148380\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/148381"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=148380"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=148380"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=148380"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}