{"id":148565,"date":"2021-04-21T10:32:31","date_gmt":"2021-04-21T08:32:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/parco-robinson-di-rende-laghetti-senzacqua-a-rischio-la-vita-degli-animali\/"},"modified":"2023-01-16T17:31:37","modified_gmt":"2023-01-16T16:31:37","slug":"404251-parco-robinson-di-rende-laghetti-senzacqua-a-rischio-la-vita-degli-animali","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/404251-parco-robinson-di-rende-laghetti-senzacqua-a-rischio-la-vita-degli-animali\/","title":{"rendered":"Parco Robinson di Rende: laghetti senz&#8217;acqua, a rischio la vita degli animali"},"content":{"rendered":"<p>RENDE &#8211; Video e foto documentano la situazione di rischio degli animali, papere, oche e soprattutto tartarughe, che vivono nei laghetti del Parco Robinson di Rende che sono letteralmente prosciugati. L&#8217;acqua \u00e8 vitale per questi esseri viventi e le associazioni animaliste e anche comuni cittadini hanno <strong>tempestivamente allertato il Comune di Rende e i vigili urbani<\/strong> per ripristinare i laghetti che sono vuote da diversi giorni.<\/p>\n<p>Nei giorni scorsi, l\u2019amministrazione comunale di Rende aveva fatto eseguire una pulizia straordinaria del laghetto viste le condizioni di sporcizia e degrado ma ora \u00e8 necessario riempirli d&#8217;acqua. Per &#8216;sorridere&#8217; potremmo scrivere che &#8220;l&#8217;acqua \u00e8 bassa e la papera non galleggia&#8221; ma in realt\u00e0 l&#8217;acqua per questi animali \u00e8 importante per la loro sopravvivenza. Secondo quanto si apprende due tartarughe sono state recuperate da una volontaria e messe in sicurezza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nelle ultime ore sono arrivate diverse segnalazioni per gli animali acquatici ospiti del Parco Robinson<\/p>\n","protected":false},"author":42,"featured_media":148566,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-148565","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/148565","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=148565"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/148565\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/148566"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=148565"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=148565"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=148565"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}