{"id":148964,"date":"2021-04-28T16:49:37","date_gmt":"2021-04-28T14:49:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/emergenza-covid-a-cosenza-vizza-assente-in-consiglio-comunale-si-dimetta\/"},"modified":"2023-01-16T17:32:04","modified_gmt":"2023-01-16T16:32:04","slug":"405312-emergenza-covid-a-cosenza-vizza-assente-in-consiglio-comunale-si-dimetta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/405312-emergenza-covid-a-cosenza-vizza-assente-in-consiglio-comunale-si-dimetta\/","title":{"rendered":"Emergenza Covid a Cosenza, \u00abVizza assente in Consiglio Comunale, si dimetta\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; Nel consiglio comunale tenutosi ieri <a href=\"https:\/\/quicosenza.it\/news\/12814\" target=\"_blank\" rel=\"noopener\">a Palazzo dei Bruzi, si \u00e8 parlato anche di Covid<\/a>. Grande assente, l\u2019Assessore Carmine Vizza, il quale avrebbe dovuto riferire in aula sui dati dei <strong>vaccini e dare supporto alle associazioni, ai medici, ai paramedici<\/strong>.<\/p>\n<p>\u00abNella seduta di marted\u00ec del Consiglio Comunale, tra i vari punti all&#8217;ordine del giorno, vi era la discussione sull&#8217;emergenza Covid nella citt\u00e0 di Cosenza. Un argomento assai importante, scivolato via frettolosamente e soprattutto segnato dalla rumorosa assenza dell&#8217;assessore comunale al &#8216;Benessere e qualit\u00e0 del tempo e dello spazio&#8217;, Carmine Vizza\u00bb. E&#8217; quanto sostiene \u2013 in una nota \u2013 il consigliere comunale e presidente della Commissione controllo e garanzia di Palazzo dei Bruzi, <strong>Enrico Morcavallo<\/strong>.<\/p>\n<p>\u00abIn collegamento, seppur tra incomprensibili e molteplici difficolt\u00e0 tecniche \u2013 aggiunge \u2013 ho preso parte al dibattito chiedendo lumi sulla mancata presenza dell&#8217;assessore, che nelle vesti di delegato del Comune ha preso parte negli ultimi mesi ad alcune riunioni della <strong>Task Force Covid-19 dell&#8217;Asp di Cosenza<\/strong>\u00bb. \u00abMi chiedo \u2013 sostiene ancora Morcavallo \u2013 come mai non abbia inteso partecipare alla riunione del civico consesso dedicata, in parte, proprio alla spinosa questione sanit\u00e0 e dunque al benessere dei cittadini\u00bb.<\/p>\n<p>\u00abInutile sottolineare \u2013 continua &#8211; quanto fosse necessario il suo apporto alla discussione, d&#8217;altro canto i contagi a Cosenza non accennano a diminuire, come dimostrano i dati e i numeri contenuti nei bollettini, la pressione sull&#8217;ospedale Annunziata pare essersi leggermente allentata ma l&#8217;emergenza resta, cos\u00ec come ancora permangono irrisolte le questioni legate all&#8217;assunzione di nuovo personale medico e sanitario in grado di rimpolpare gli organici ridotti all&#8217;osso di chi combatte, in trincea, contro il virus\u00bb. E conclude: \u00abpreso atto del silenzio di Vizza, ho ritenuto opportuno chiederne le dimissioni. <strong>Il suo comportamento non \u00e8 accettabile e giustificabile<\/strong>\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo riporta in una nota il consigliere comunale Enrico Morcavallo. L\u2019Assessore avrebbe dovuto riferire in aula sui dati dei vaccini e dare supporto alle associazioni, ai medici, ai paramedici<\/p>\n","protected":false},"author":58,"featured_media":148965,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-148964","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/148964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=148964"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/148964\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/148965"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=148964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=148964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=148964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}