{"id":149438,"date":"2021-05-07T18:13:11","date_gmt":"2021-05-07T16:13:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/trebisacce-ricerche-a-tappeto-del-47nne-scomparso-ci-circa-anche-in-un-laghetto\/"},"modified":"2023-01-16T17:32:36","modified_gmt":"2023-01-16T16:32:36","slug":"406597-trebisacce-ricerche-a-tappeto-del-47nne-scomparso-ci-circa-anche-in-un-laghetto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/406597-trebisacce-ricerche-a-tappeto-del-47nne-scomparso-ci-circa-anche-in-un-laghetto\/","title":{"rendered":"Trebisacce, ricerche a tappeto del 47enne scomparso. Si cerca anche in un laghetto"},"content":{"rendered":"<p>TREBISACCE (CS) &#8211; Continuano a tappeto, oramai dalle ore 9.30 di questa mattina, le ricerche di\u00a0<strong>Francesco Rusciani, <\/strong>47enne scomparso dalla serata di ieri in <strong>localit\u00e0 Broglio nel comune di Trebisacce<\/strong>. A cercare l&#8217;uomo sono le squadre dei vigili del fuoco del comando di Cosenza, distaccamento di Castrovillari e volontari di Trebisacce. A collaborare nelle ricerche anche i <strong>carabinieri e volontari di Protezione Civile<\/strong>. L&#8217;allarme \u00e8 stato lanciato dai familiari (in particolare dalla sorella con cui vive) che non hanno visto rientrare il loro congiunto casa.<\/p>\n\n<p>Sul posto sopraggiunti in <strong>supporto nucleo cinofili<\/strong> dei vigili del fuoco del comando di Matera ed elicottero DRAGO VF26 del reparto volo di Salerno. Alle ore 18.00 \u00e8 arrivato anche il<strong> nucleo sommozzatori<\/strong> del comando di Reggio Calabria per ulterior<strong>i ricerche in un laghetto artificiale<\/strong> ad uso irrigazione situato a poca distanza dalla zona di intervento. A coordinare le operazioni di soccorso unit\u00e0 con qualifica TAS (topografia applicata al soccorso) con automezzo AF\/UCL (unit\u00e0 di comando locale) proveniente dalla sede centrale di Cosenza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ricerche a tappeto da parte di vigili del fuoco, carabinieri e uomini della protezione civile. Ancora senza esito<\/p>\n","protected":false},"author":55,"featured_media":149439,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-149438","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/149438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=149438"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/149438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/149439"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=149438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=149438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=149438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}