{"id":149560,"date":"2021-05-10T18:00:18","date_gmt":"2021-05-10T16:00:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cassano-scritte-contro-i-carabinieri-sui-muri-il-sindaco-atto-ignobile\/"},"modified":"2023-01-16T17:32:44","modified_gmt":"2023-01-16T16:32:44","slug":"406977-cassano-scritte-contro-i-carabinieri-sui-muri-il-sindaco-atto-ignobile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/406977-cassano-scritte-contro-i-carabinieri-sui-muri-il-sindaco-atto-ignobile\/","title":{"rendered":"Cassano, scritte contro i carabinieri sui muri. il sindaco &#8220;atto ignobile&#8221;"},"content":{"rendered":"<p>CASSANO ALLO IONIO (CS) &#8211; Il sindaco <strong>Gianni Papasso<\/strong>, a nome dell&#8217;amministrazione comunale e della citt\u00e0 intera, esprime solidariet\u00e0 ai carabinieri della Tenenza di Cassano &#8220;per <strong>l&#8217;atto di vilt\u00e0 e vigliaccheria<\/strong> sub\u00ecto nel fine settimana quando sono comparse delle ignobili scritte sulle mura della delegazione municipale di Sibari. Censuriamo &#8211; ha scritto il primo cittadino su un post pubblicato su Facebook &#8211; questo atto ed <strong>esprimiamo affetto e vicinanza ai Carabinieri<\/strong> che operano con dedizione e costanza in un territorio difficile come il nostro. <strong>Abbiamo gi\u00e0 provveduto a far cancellare quelle orribili frasi<\/strong>. Daremo ai carabinieri tutto il nostro supporto affinch\u00e9 &#8211; ha concluso Papasso &#8211; Noi tutti abbiamo fiducia smisurata nei loro confronti e per questo riteniamo doveroso un atto di forte denuncia contro queste azioni che traboccano di odio e ignoranza&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-406981 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/05\/carabineri-ladri.jpg\" alt=\"\" width=\"578\" height=\"433\" title=\"\"><\/p>\n<p>&#8220;La comunit\u00e0 di Cassano \u2013 ha detto ancora Papasso \u2013 <strong>non ha intenzione di tacere davanti a chi pensa di vilipendere i Carabinieri<\/strong>. Noi tutti abbiamo fiducia smisurata nei loro confronti e per questo riteniamo doveroso un atto di forte denuncia contro queste azioni che traboccano di odio e ignoranza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Abbiamo gi\u00e0 provveduto a far cancellare quelle orribili frasi &#8211; ha detto Giovanni Papasso &#8211; tutta la nostra solidariet\u00e0 all&#8217;Arma&#8221;<\/p>\n","protected":false},"author":58,"featured_media":149561,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-149560","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/149560","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=149560"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/149560\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/149561"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=149560"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=149560"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=149560"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}