{"id":149780,"date":"2021-05-16T08:00:28","date_gmt":"2021-05-16T06:00:28","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/torna-cosenza-comics-special-guest-cristina-scabbia-dei-lacuna-coil\/"},"modified":"2023-01-16T17:32:58","modified_gmt":"2023-01-16T16:32:58","slug":"407522-torna-cosenza-comics-special-guest-cristina-scabbia-dei-lacuna-coil","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/407522-torna-cosenza-comics-special-guest-cristina-scabbia-dei-lacuna-coil\/","title":{"rendered":"Torna &#8220;Cosenza Comics&#8221;: special guest Cristina Scabbia dei Lacuna Coil"},"content":{"rendered":"<p>COSENZA &#8211; Si terr\u00e0 online e durer\u00e0 quattro giorni, <strong>dal 20 al 23 maggio<\/strong>, l\u2019edizione 2021 di Cosenza Comics. Parteciperanno ospiti connessi da tutta Italia e non solo, che intratterranno e interagiranno con il pubblico in contemporanea su Facebook, Youtube e Twitch. Un&#8217;edizione pi\u00f9 ricca dell\u2019anno precedente, con <strong>50 ospiti<\/strong> pronti a celebrare le novit\u00e0 pi\u00f9 importanti del mondo della pop culture.<\/p>\n<p><strong>Si torner\u00e0 a parlare di Lego <\/strong>con l\u2019associazione Itlug e con Brick Generation Days, organizzatori fra le altre cose del Contest a premi \u201cTime Travels\u201d. Interverranno <strong>ospiti dal mondo del fumetto<\/strong> e dell\u2019illustrazione come Teresa Radice e Stefano Turconi, Daniel Cuello, Tatai Lab, Stefano Bosi, Sergio Olivotti, Moreno Chiacchiera, Elisa Macellari. Si parler\u00e0 di editoria e sceneggiatura con Lucio Staiano, Davide Costa, Leonardo Valenti e Jundo (la nuova piattaforma in stile Netflix pensata per leggere fumetti). Si esplorer\u00e0 il <strong>mondo delle serie tv<\/strong> dal punto di vista di Marina Pierri, critica televisiva e autrice del libro \u201cEroine\u201d e insieme ad Empira, uno dei pi\u00f9 importanti fan club dedicati a Guerre Stellari, che analizzer\u00e0 il <strong>fenomeno Disney+<\/strong> a partire dalla serie evento \u201cThe Mandalorian\u201d fino ai nuovi prodotti targati Star Wars e di prossima uscita.<\/p>\n<p>Non mancheranno addetti ai lavori nel <strong>mondo dell\u2019animazione<\/strong> come Nicola Sammarco e Giulia Carbone.<br \/>\nL\u2019area dedicata al cinema e al doppiaggio vedr\u00e0 la partecipazione di Alessandro Budroni e Giuppy Izzo (doppiatori nella serie tv \u201cStranger Things\u201d). Special guest dell\u2019evento sar\u00e0 <strong>Cristina Scabbia, cantante e frontwoman dei Lacuna Coil.<\/strong><\/p>\n<p>Si torner\u00e0 a parlare di <strong>videogiochi<\/strong> insieme allo youtuber Dadobax e a Pok\u00e9mon Millenium, per celebrare il venticinquesimo anniversario del brand. Non mancheranno i panel dedicati anche alla scienza, alla tecnologia e ai social insieme a Willy Guasti, Francesco Barberini, Licia Troisi e Young Montemagno, l\u2019esilarante e geniale personaggio-parodia! Come da tradizione, ampio spazio verr\u00e0 dedicato anche <strong>al modellismo e ai giochi da tavolo.<\/strong><\/p>\n<p>Novit\u00e0 anche dalla scuola di Arti Visive Nero Su Bianco di Cosenza che presenter\u00e0 per l\u2019occasione la nuova etichetta \u201cNero Su Bianco Press\u201d e il primo fumetto che vedr\u00e0 protagonisti le mascotte dell\u2019evento: i lupi &#8220;Kepler e Alariko&#8221;, realizzato da Carlo Lauro e Roberto Megna. Grazie a loro Cosenza Comics diventer\u00e0 un fumetto a tutti gli effetti. Infine, una delle novit\u00e0 pi\u00f9 accattivanti, sar\u00e0 la <strong>mostra interattiva \u201cSegni dal Futuro\u201d<\/strong>; una vera e propria stanza digitale e interattiva in cui poter ammirare i lavori realizzati da trenta artisti italiani e fare un tuffo nel passato ammirando i poster storici della fiera. La mostra, verr\u00e0 inaugurata il 20 maggio,<strong> sar\u00e0 visitabile fino al 20 giugno<\/strong> da casa attraverso il browser. Tanti altri sono gli ospiti che si troveranno in questa grandissima edizione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La settima edizione di Cosenza Comics and Games celebrer\u00e0 il tema \u201cBeyond\u201d: oltre. Un invito a guardare al futuro e a fruire dei nuovi mezzi di condivisione degli eventi e delle interazioni con il pubblico<\/p>\n","protected":false},"author":42,"featured_media":149781,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34],"tags":[19],"class_list":["post-149780","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/149780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=149780"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/149780\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/149781"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=149780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=149780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=149780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}