{"id":150368,"date":"2021-05-25T17:35:53","date_gmt":"2021-05-25T15:35:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/furti-di-pc-e-atti-vandalici-nelle-scuole-denunciati-5-ragazzi\/"},"modified":"2023-01-16T17:33:37","modified_gmt":"2023-01-16T16:33:37","slug":"409011-furti-di-pc-e-atti-vandalici-nelle-scuole-denunciati-5-ragazzi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/409011-furti-di-pc-e-atti-vandalici-nelle-scuole-denunciati-5-ragazzi\/","title":{"rendered":"Furti di pc e atti vandalici nelle scuole, denunciati 5 ragazzi"},"content":{"rendered":"<p>CROTONE &#8211; I carabinieri della Compagnia di Crotone hanno denunciato cinque ragazzi per <strong>ricettazione di materiale elettronico e deturpamento ed imbrattamento<\/strong>. Le denunce scaturiscono dalle indagini che i militari hanno avviato dopo alcuni furti portati a segno, nei giorni scorsi, all&#8217;interno di due istituti di istruzione. Le perquisizioni domiciliari hanno consentito, secondo quanto si \u00e9 appreso, di trovare, nella disponibilit\u00e0 di alcuni dei ragazzi denunciati, <strong>sette tablet e due notebook, utilizzati dalle scuole per la didattica a distanza<\/strong>. Dopo il riconoscimento da parte dei relativi dirigenti scolastici, gli ausili sono stati loro restituiti. Inoltre, gli accertamenti svolti nell&#8217;immediatezza dai carabinieri hanno consentito di identificare in due dei cinque ragazzi i responsabili del deturpamento ed imbrattamento, con scritte e disegni, della pavimentazione di una piazza e del muro di un edificio di culto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le perquisizioni domiciliari hanno consentito di rinvenire sette tablet e due notebook, utilizzati dalle scuole per la didattica a distanza<\/p>\n","protected":false},"author":58,"featured_media":150369,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-150368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=150368"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/150369"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=150368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=150368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=150368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}