{"id":150550,"date":"2021-05-29T05:30:16","date_gmt":"2021-05-29T03:30:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/castrovillari-uccide-la-madre-e-tenta-di-aggredire-anche-il-padre-chiarire-semi-infermita\/"},"modified":"2023-01-16T17:33:49","modified_gmt":"2023-01-16T16:33:49","slug":"409510-castrovillari-uccide-la-madre-e-tenta-di-aggredire-anche-il-padre-chiarire-semi-infermita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/409510-castrovillari-uccide-la-madre-e-tenta-di-aggredire-anche-il-padre-chiarire-semi-infermita\/","title":{"rendered":"Omicidio di Castrovillari, il padre ha disarmato il figlio &#8220;chiarire la seminfermit\u00e0&#8221;"},"content":{"rendered":"<p>CASTROVILLARI (CS9 &#8211; Paolo Emilio Sisci, il 32enne che gioved\u00ec a Castrovillari <a href=\"https:\/\/quicosenza.it\/news\/13028\" target=\"_blank\" rel=\"noopener\">ha ucciso a coltellate la madre<\/a> Filomena Silvestri, di 65, <strong>avrebbe tentato anche di aggredire il padre, Alberto<\/strong>, quest&#8217;ultimo nel difendersi <strong>avrebbe fatto cadere il coltello<\/strong> che l&#8217;uomo aveva in mano. Alberto Sisci ha poi <strong>trovato scampo rifugiandosi sul terrazzo<\/strong> dell&#8217;appartamento della famiglia in cui \u00e8 stato commesso il delitto fino all&#8217;arrivo dei carabinieri che hanno arrestato il figlio. Quest&#8217;ultimo, secondo quanto si \u00e8 appreso in ambienti della Procura, non \u00e8 stato ancora sentito dai magistrati che coordinano il lavoro dei carabinieri della Compagnia di Castrovillari.<\/p>\n<p><strong>Da chiarire, dunque, resta il movente che ha spinto Paolo Sisci ad avventarsi sulla madre colpendola con numerose coltellate<\/strong> in varie parti del corpo. I magistrati attendono dunque gli esiti dell&#8217;autopsia, che dovrebbe essere effettuata all&#8217;inizio della prossima settimana, e l&#8217;interrogatorio di convalida per cercare di capire i motivi del delitto. Al riguardo, Sisci \u00e8 anche stato sottoposto a perizia psichiatrica, visto che si parlava di una sofferenza psichiatrica dell&#8217;uomo, ma <strong>dagli esami non sarebbero emerse particolari<\/strong>. La Procura, comunque, ritiene necessario condurre altri accertamenti anche su questo fronte.<\/p>\n<h4>Il legale del 32enne &#8220;chiarire la semiinfermit\u00e0&#8221;<\/h4>\n<p>&#8220;I pettegolezzi di corridoio ci dicono che, negli ambienti degli inquirenti, non ci sia una forte convinzione nella problematica psichiatrica cos\u00ec marcata da poter sostenere l&#8217;incapacit\u00e0 di intendere e di volere&#8221;. A dirlo \u00e8 <strong>l&#8217;avvocato Roberto Laghi difensore dell&#8217;omicida trentaduenne Paolo Emilio Sisci. <\/strong>\u00a0&#8220;Noi allo stato &#8211; aggiunge il legale &#8211; non abbiamo avuto ancora accesso, per come peraltro sar\u00e0 nostro diritto, alle dichiarazioni rese sia nella forma di interrogatorio, sia nella forma di spontanee dichiarazioni dal nostro assistito. Allo stato sembrerebbe che ancora non sia stata fissato l&#8217;esame autoptico.<strong> L&#8217;autopsia<\/strong>, pur essendo evidente la causa della morte della povera madre, sar\u00e0 molto importante per capire questa sorta di automatismo, questo elevato numero di fendenti dati. Quanti colpi sono? Quali parti vitali hanno attinto? Perch\u00e9 gi\u00e0 questa geografia della lesivit\u00e0 potrebbe essa stessa dare <strong>uno spaccato sulla situazione psicologica<\/strong>, psichiatrica di questo giovane che ha creato un problema cos\u00ec enorme&#8221;.<\/p>\n<p>L&#8217;avvocato difensore di Sisci <strong>non ritiene molto importante l&#8217;eventuale confessione<\/strong>. &#8220;Ritengo che non sia molto importante o meno un&#8217;eventuale confessione, c&#8217;\u00e8 &#8211; sottolinea &#8211; una situazione di flagranza o di quasi flagranza per cui l&#8217;ipotesi della attribuibilit\u00e0 al giovane dell&#8217;omicidio della madre mi sembra appunto, allo stato, sia fuori discussione. C&#8217;\u00e8 da chiarire che l&#8217;incapacit\u00e0 di intendere e di volere, al momento dell&#8217;atto, potrebbe escludere la punibilit\u00e0, ma poi ci sarebbe un problema di misura di sicurezza eventualmente da scontare, l&#8217;altro problema, ben significativo, \u00e8 la <strong>semiinfermit\u00e0<\/strong> che vale come una sorta di attenuante che, allo stato, <strong>rimane tutta da dimostrare<\/strong> e da capirne il peso sotto il profilo del bilanciamento tra aggravanti e attenuanti. Ovviamente la famiglia Sisci \u00e8 completamente distrutta. E&#8217; in una situazione di sgomento totale perch\u00e9 si tratta di una tragedia immensa e, soprattutto, perch\u00e9 si sono aperte le porte del carcere per un congiunto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il legale del 32enne dopo che la perizia ha escluso i disturbi psichici &#8220;andranno capite e valutate le motivazioni del gesto&#8221;<\/p>\n","protected":false},"author":58,"featured_media":150551,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-150550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=150550"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/150551"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=150550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=150550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=150550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}