{"id":150863,"date":"2021-06-04T17:32:04","date_gmt":"2021-06-04T15:32:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/crollo-sulla-statale-106-chiesto-il-processo-per-progettista-e-collaudatore\/"},"modified":"2023-01-16T17:34:11","modified_gmt":"2023-01-16T16:34:11","slug":"410262-crollo-sulla-statale-106-chiesto-il-processo-per-progettista-e-collaudatore","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/410262-crollo-sulla-statale-106-chiesto-il-processo-per-progettista-e-collaudatore\/","title":{"rendered":"Crollo sulla Statale 106: chiesto il processo per progettista e collaudatore"},"content":{"rendered":"<p>CATANZARO &#8211; La Procura di Catanzaro ha chiesto il rinvio a giudizio di due persone e l&#8217;assoluzione di una terza nell&#8217;ambito dell&#8217;inchiesta sul crollo di un muro di contenimento di una rampa di accesso al nuovo tracciato della<strong> statale 106 in localit\u00e0 Germaneto di Catanzaro<\/strong>. Il processo \u00e8 stato chiesto dal pm Francesco Bordonali per <strong>Alessio Marino Ajmone<\/strong> Cat, di 60 anni, di Milano, ingegnere progettista della Astaldi Spa e per <strong>Michele Mele<\/strong>, di 79 anni, di Bari, ingegnere collaudatore statico. Il pm ha chiesto<strong> l&#8217;assoluzione<\/strong> per non aver commesso il fatto nei confronti di<strong> Antonio Bevilacqua<\/strong>, di 56 anni, di Palermo, ingegnere, direttore dei lavori del tratto stradale. Sui rinvii a giudizio e sulla posizione dell&#8217;abbreviato il gup Antonio Battaglia decider\u00e0 il prossimo 15 ottobre.<\/p>\n<p>Nel corso dell&#8217;udienza davanti al Gup, Bevilacqua, difeso dall&#8217;avvocato Nicola Carratelli, ha sostenuto che in qualit\u00e0 di direttore dei lavori non aveva nessun obbligo di rivedere gli elaborati del progetto ed ha rivendicato la correttezza del proprio operato. I difensori di Aimone e Mele &#8211; gli avvocati Aldo Casalinuovo, Francesca Carangelo e Francesco Tocci &#8211; hanno chiesto il proscioglimento perch\u00e9 il fatto non sussiste.<\/p>\n<h3>Per i legali &#8220;scivolamento del muro avvenuto a giugno&#8221;<\/h3>\n<p>Secondo i legali al primo manifestarsi della fessurazione,<strong> il 26 maggio 2017, l&#8217;area \u00e8 stata interdetta al traffico e lo scivolamento del muro \u00e8 avvenuto a giugno<\/strong>. Manca, secondo i difensori, l&#8217;elemento del pericolo per la pubblica incolumit\u00e0, elemento costitutivo del reato di disastro colposo. Nella loro relazione, i periti nominati dal gup, sentiti il 18 gennaio scorso, hanno sostenuto che il crollo della rampa di accesso \u00e8 stato causato da un <strong>errore progettuale<\/strong> legato a un cattivo sistema di drenaggio dell&#8217;acqua, senza tubi di scolo, che ha causato un letale ristagno di acqua. Nel processo si sono costituite<strong> parti civili l&#8217;Anas e il Codacons<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alessio Marino Ajmone e Michele Mele sono stati rinviati a giudizio per il crollo del muro di contenimento a Catanzaro, avvenuto il 26 maggio 2017<\/p>\n","protected":false},"author":58,"featured_media":150864,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-150863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=150863"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150863\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/150864"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=150863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=150863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=150863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}