{"id":150894,"date":"2021-06-05T14:20:19","date_gmt":"2021-06-05T12:20:19","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/scalea-giornata-mondiale-dellambiente-nuovi-alberi-per-seminare-speranza\/"},"modified":"2023-01-16T17:34:13","modified_gmt":"2023-01-16T16:34:13","slug":"410336-scalea-giornata-mondiale-dellambiente-nuovi-alberi-per-seminare-speranza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/410336-scalea-giornata-mondiale-dellambiente-nuovi-alberi-per-seminare-speranza\/","title":{"rendered":"Scalea: Giornata Mondiale dell&#8217;Ambiente, nuovi alberi per &#8216;seminare speranza&#8217;"},"content":{"rendered":"<p>SCALEA (CS) &#8211; Un modo concreto per celebrare la Giornata mondiale dell&#8217;Ambiente, dando spazio a nuova vita, alberi, in un terreno che era diventato discarica di materiale di risulta e che da oggi offre una speranza. Saranno ben 200 gli alberi da frutto che potranno crescere e dare un futuro diverso ad un angolo del centro tirrenico. A lanciare l&#8217;iniziativa la cooperativa sociale &#8220;Progetto Germano&#8221; nata nel settembre del 2013 il cui responsabile \u00e8 Fabio Cifuni che spiega come oggi siano stati piantati alberi di fico e melograno, ma nei prossimi giorni la piantumazione si allargher\u00e0 per tutto il terreno che gi\u00e0 ospita pomodori, peperoncini e le cipolle di Tropea.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-410338 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/06\/Scalea-attivita-giornata-mondiale-ambiente-02.jpg\" alt=\"\" width=\"599\" height=\"459\" title=\"\"><\/p>\n<p>Gli alberi sono stati donati da un&#8217;azienda che si occupa di forestazione e cos\u00ec, insieme al Comune e ad altri soggetti e cittadini, \u00e8 partita l&#8217;operazione: &#8220;Nel terreno non si usano concimi chimici e a volte vi lavorano anche dei detenuti. Un sistema che funziona davvero &#8211; spiega Cifuni &#8211; perch\u00e9 chi viene qui a fare questa esperienza cambia il suo modo di vivere&#8221;. Unire la bellezza e l&#8217;importanza di dar vita ad un nuovo ambiente e inserire chi \u00e8 svantaggiato in un contesto lavorativo \u00e8 un connubio importante. Insieme alla cooperativa operano le Acli, il Movimento lavoratori di azione cattolica e il Progetto Policoro della Cei, che si occupa di dignit\u00e0, vangelo, lavoro e giovani.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-410337 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/06\/Scalea-attivita-giornata-mondiale-ambiente-01.jpg\" alt=\"\" width=\"595\" height=\"492\" title=\"\"><\/p>\n<p>&#8220;Siamo davvero contenti di aver iniziato questa avventura, difficile all&#8217;inizio, quando abbiamo lottato con persone che proprio volevano bloccarci, ma che davvero adesso ci fa sentire utili al territorio. Abbiamo anche inventato un marchio, &#8220;<strong>Scaliando<\/strong>&#8220;, che contraddistingue i diversi prodotti tipici che produciamo e diffondiamo in tutta Italia&#8221;.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-410341 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/06\/Scalea-attivita-giornata-mondiale-ambiente-05.jpg\" alt=\"\" width=\"538\" height=\"500\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-410340 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/06\/Scalea-attivita-giornata-mondiale-ambiente-04.jpg\" alt=\"\" width=\"538\" height=\"360\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-410342 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/06\/Scalea-attivita-giornata-mondiale-ambiente-06.jpg\" alt=\"\" width=\"541\" height=\"347\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuovi alberi, fico e melograno, una ventina piantati questa mattina in un terreno occupato abusivamente che era diventato una discarica<\/p>\n","protected":false},"author":42,"featured_media":150895,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-150894","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=150894"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/150894\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/150895"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=150894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=150894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=150894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}