{"id":151032,"date":"2021-06-12T15:00:29","date_gmt":"2021-06-12T13:00:29","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/lunical-riparte-il-rientro-in-ateneo-raccontato-dagli-studenti\/"},"modified":"2023-01-16T17:34:23","modified_gmt":"2023-01-16T16:34:23","slug":"410679-lunical-riparte-il-rientro-in-ateneo-raccontato-dagli-studenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/410679-lunical-riparte-il-rientro-in-ateneo-raccontato-dagli-studenti\/","title":{"rendered":"L&#8217;UniCal riparte: il rientro in ateneo raccontato dagli studenti"},"content":{"rendered":"<p>ARCAVACATA (CS) &#8211; <strong>Com&#8217;\u00e8 andato il rientro all&#8217;UniCal?<\/strong> Il racconto di queste ultime settimane nel video realizzato con gli studenti dei corsi di laurea in Comunicazione e Dams e Comunicazione e Tecnologie dell&#8217;informazione.<\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/sYi93gsYlcE\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>VIDEO &#8211; Il racconto di queste ultime settimane nel video realizzato con gli studenti dei corsi di laurea in Comunicazione<\/p>\n","protected":false},"author":58,"featured_media":151033,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-151032","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151032","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=151032"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151032\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/151033"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=151032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=151032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=151032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}