{"id":151106,"date":"2021-06-10T05:52:43","date_gmt":"2021-06-10T03:52:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/edifici-pericolosi-ai-laghi-di-sibari-ordinanza-del-sindaco-per-metterli-in-sicurezza\/"},"modified":"2023-01-16T17:34:26","modified_gmt":"2023-01-16T16:34:26","slug":"410880-edifici-pericolosi-ai-laghi-di-sibari-ordinanza-del-sindaco-per-metterli-in-sicurezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/410880-edifici-pericolosi-ai-laghi-di-sibari-ordinanza-del-sindaco-per-metterli-in-sicurezza\/","title":{"rendered":"Edifici pericolosi ai Laghi di Sibari, ordinanza del sindaco per metterli in sicurezza"},"content":{"rendered":"<p>CASSANO IONIO (CS) &#8211; Il sindaco di Cassano Gianni Papasso ha firmato un&#8217;ordinanza rivolta ai proprietari degli immobili situati nei pressi del Centro commerciale dei Laghi di Sibari per la messa in sicurezza degli edifici al fine di scongiurare un pericolo per la pubblica incolumit\u00e0. Il provvedimento fa seguito ad un rapporto del Comando di <strong>Polizia Locale<\/strong> dopo un sopralluogo presso il Centro commerciale &#8220;dove era stato reiteratamente segnalato lo stato degradato di alcuni edifici e constata l&#8217;effettiva realt\u00e0 di quanto segnalato in quanto presentavano intonaci esterni ammalorati e tinteggiature fatiscenti e che, pertanto, risultano necessari <strong>interventi urgenti per la messa in sicurezza degli edifici<\/strong> in questione per evitare <strong>caduta di calcinacci e intonaci<\/strong> che possano mettere in pericolo l&#8217;incolumit\u00e0 dei passanti&#8221;.<\/p>\n<p>Il sindaco ha ordinato <strong>ai 75 proprietari e locatari di 154 immobili<\/strong> siti nel &#8220;Centro Commerciale&#8221; &#8220;di mettere in sicurezza gli edifici onde evitare rischi per l&#8217;incolumit\u00e0 dei passanti, di procedere alla pulitura degli intonaci e\/o il rinnovo delle tinteggiature, sia delle facciate che delle pareti comunque esterne agli edifici prospicienti aree pubbliche e di ripristinare il perfetto funzionamento dei pluviali&#8221;. Nell&#8217;atto, si dispone, inoltre, che &#8220;la tinta delle pareti esterne, prospicienti le aree pubbliche, richiami il colore originario.<strong> I lavori di ripulitura o di rinnovo delle pareti dovranno essere eseguiti entro il 30 giugno prossimo&#8221;.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>I 75 proprietari e locatari di 154 immobili sono chiamati a mettere in sicurezza gli edifici onde evitare rischi per l&#8217;incolumit\u00e0 dei passanti<\/p>\n","protected":false},"author":42,"featured_media":151107,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-151106","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=151106"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151106\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/151107"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=151106"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=151106"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=151106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}