{"id":151368,"date":"2021-06-15T14:35:42","date_gmt":"2021-06-15T12:35:42","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragedia-raganello-slitta-il-processo-inopportuno-aprire-il-dibattimento\/"},"modified":"2023-01-16T17:34:44","modified_gmt":"2023-01-16T16:34:44","slug":"411532-tragedia-raganello-slitta-il-processo-inopportuno-aprire-il-dibattimento","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/411532-tragedia-raganello-slitta-il-processo-inopportuno-aprire-il-dibattimento\/","title":{"rendered":"Tragedia Raganello, slitta il processo &#8220;inopportuno aprire il dibattimento&#8221;"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Slitta al <strong>prossimo 26 novembre<\/strong> l&#8217;inizio, che era previsto per stamane, del processo per la tragedia avvenuta nelle <a href=\"https:\/\/quicosenza.it\/news\/13135\" target=\"_blank\" rel=\"noopener\">gole del Raganello<\/a> dove, il 20 agosto 2018, a causa di una improvvisa ondata di piena, morirono dieci persone, nove escursionisti e una guida. Il rinvio \u00e8 motivato dalla mancanza di notifica ad alcuni imputati e ad alcune parti offese e dal fatto, evidenziato dal collegio difensivo, che pende un&#8217;impugnativa della Procura generale sulle sentenze di non luogo a procedere che riguardano le posizioni di un po&#8217; di tutti gli imputati del procedimento.<\/p>\n<h3>&#8220;Inopportunit\u00e0 ad aprire il dibattimento&#8221;<\/h3>\n<p>&#8220;In attesa che si esprima la Corte d&#8217;Appello che \u00e8 competente su questo tipo di impugnativa, abbiamo segnalato al collegio giudicante &#8211; ha spiegato l&#8217;avvocato Riccardo Rosa, difensore, insieme all&#8217;avvocato Roberto Laghi, del sindaco di Civita, Alessandro Tocci &#8211; l&#8217;inopportunit\u00e0 di aprire il dibattimento perch\u00e9 qualora dovesse essere accolta l&#8217;impugnativa prodotta dal Procuratore generale della Corte d&#8217;Appello contestualmente <strong>si potrebbero stabilire due procedimenti paralleli con gli stessi testimoni<\/strong>, con pi\u00f9 o meno le stesse contestazioni e le stesse parti. Quindi noi, come collegio difensivo &#8211; ha aggiunto il legale &#8211; abbiamo ritenuto opportuno chiedere di differire l&#8217;apertura di questo processo all&#8217;esito della valutazione della Corte d&#8217;Appello sull&#8217;impugnativa.<\/p>\n<p>Il 12 aprile scorso il Gup, Biagio Politano, aveva deciso il <strong>rinvio a giudizio per 6 dei 14 imputati<\/strong>, aveva a<strong>ssolto i tre imputati (Antonio Luca De Salvo, Luca D&#8217;Alba e Roberto De Marco)<\/strong> che avevano optato per il rito abbreviato e aveva disposto il <strong>non luogo a procedere per gli altri cinque imputati<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il collegio difensivo chiede il rinvio &#8211; per motivi tecnico giuridici &#8211; al prossimo 26 novembre. L&#8217;inizio in aula era previsto per stamattina<\/p>\n","protected":false},"author":58,"featured_media":151369,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-151368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=151368"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151368\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/151369"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=151368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=151368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=151368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}