{"id":151692,"date":"2021-06-20T13:06:37","date_gmt":"2021-06-20T11:06:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cetraro-paura-per-il-giudice-massimo-lento-colto-da-un-malore-in-spiaggia\/"},"modified":"2023-01-16T17:35:06","modified_gmt":"2023-01-16T16:35:06","slug":"412327-cetraro-paura-per-il-giudice-massimo-lento-colto-da-un-malore-in-spiaggia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/412327-cetraro-paura-per-il-giudice-massimo-lento-colto-da-un-malore-in-spiaggia\/","title":{"rendered":"Cetraro, paura per il giudice Massimo Lento colto da un malore in spiaggia"},"content":{"rendered":"<p>CETRARO (CS) &#8211; Il magistrato <strong>Massimo Lento<\/strong>, da pochi giorni nominato presidente del tribunale di Castrovillari, \u00e8 stato colto da un malore mentre si trovava in spiagga a Cetraro, in localit\u00e0 Lampetia. Secondo quanto si apprende Lento stava per entrare in acqua quando si \u00e8 <strong>accasciato sulla spiaggia<\/strong>. Il primo soccorso \u00e8 stato effettuato da un carabiniere libero dal servizio, dopo che la moglie e alcuni bagnanti che hanno assistito alla scena, hanno lanciato l&#8217;allarme. E&#8217; successivamente atterrato l&#8217;elicottero del 118 e sul posto \u00e8 arrivata anche un&#8217;ambulanza. <strong>Massimo Lento si trova ora ricoverato in ospedale all&#8217;Annunziata di Cosenza<\/strong>. Al momento non si conoscono le condizioni del giudice ma <strong>non sarebbe in pericolo di vita.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da poco nominato presidente del Tribunale di Castrovillari, Massimo Lento \u00e8 stato trasportato all&#8217;ospedale di Cosenza<\/p>\n","protected":false},"author":42,"featured_media":151693,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-151692","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=151692"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151692\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/151693"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=151692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=151692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=151692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}