{"id":151890,"date":"2021-06-24T08:32:37","date_gmt":"2021-06-24T06:32:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/parco-della-sila-pubblicata-graduatoria-per-la-concessione-di-patrocini-onerosi\/"},"modified":"2023-01-16T17:35:19","modified_gmt":"2023-01-16T16:35:19","slug":"412868-parco-della-sila-pubblicata-graduatoria-per-la-concessione-di-patrocini-onerosi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/412868-parco-della-sila-pubblicata-graduatoria-per-la-concessione-di-patrocini-onerosi\/","title":{"rendered":"Parco della Sila, pubblicata graduatoria per la concessione di patrocini onerosi"},"content":{"rendered":"<p>LORICA \u2013 E&#8217; stata pubblicata stamattina la graduatoria provvisoria degli ammessi a patrocinio oneroso ai sensi del \u201cBando Pubblico per la concessione di patrocini onerosi a sostegno di progetti\/iniziative promossi da <strong>Enti, Associazioni, Istituti, Cooperative e soggetti privati senza scopo di lucro<\/strong> per lo svolgimento di attivit\u00e0 o realizzazione di interventi compatibili con le finalit\u00e0 del Parco\u201d, pubblicato lo scorso 15 febbraio 2021. La Commissione esaminatrice ha valutato le istanze pervenute da oltre <strong>60 Soggetti pubblici e privati <\/strong>senza scopo di lucro proponenti altrettante iniziative e manifestazioni da svolgersi nel territorio dei Comuni ricompresi nel Parco Nazionale della Sila.<\/p>\n<p>Molto ampia la gamma di tematiche entro le quali i richiedenti erano tenuti ad elaborare le loro proposte:<br \/>\n&#8211; Recupero e valorizzazione del patrimonio socio\u2013culturale ed etno\u2013demo\u2013antropologico delle comunit\u00e0 locali del Parco;<br \/>\n&#8211; Promozione di eventi e manifestazioni che valorizzino l\u2019immagine e l\u2019identit\u00e0 del Parco;<br \/>\n&#8211; Promozione di attivit\u00e0 di animazione socio\u2013culturale, di sensibilizzazione, di educazione ambientale permanente delle comunit\u00e0 locali del Parco;<br \/>\n&#8211; Promozione di attivit\u00e0 di ricreazione, di impiego del tempo libero e di attivit\u00e0 sportive ecocompatibili che favoriscono la fruizione del Parco;<br \/>\n&#8211; Promozione di attivit\u00e0 che valorizzino il patrimonio eno\u2013gastronomico prodotto nel territorio del Parco.<\/p>\n<p>L\u2019Ente Parco, in fase di adozione del bilancio di previsione 2021, ha stabilito di destinare alle suddette finalit\u00e0 la somma complessiva di 80.000,00 euro \u2013 il doppio rispetto alle somme stabilite negli anni precedenti \u2013 per supportare, attraverso la pubblicazione di apposito bando pubblico, la realizzazione di attivit\u00e0 volte a favorire la promozione, divulgazione e valorizzazione degli aspetti naturali, culturali e tradizionali dell\u2019area protetta.<\/p>\n<p>Un aiuto concreto e fattivo \u2013 soprattutto in questa fase di ripartenza &#8211; per coloro i quali si impegnano fattivamente sul territorio, offrendo a cittadini e visitatori occasioni di svago e intrattenimento, spaziando in molteplici ambiti di rilevanza sociale, economica, storica, culturale, sportiva, artistica o scientifica per la Sila.<\/p>\n<p><strong>52 gli eventi patrocinati (<a href=\"https:\/\/quicosenza.it\/news\/13204\" target=\"_blank\" rel=\"noopener\">QUI la graduatoria<\/a>),<\/strong> che si svolgeranno entro la fine dell\u2019anno nei Comuni e nelle localit\u00e0 turistiche silane delle tre province di<strong> Catanzaro, Cosenza e Crotone<\/strong>, nel rispetto dei vincoli e del regime di salvaguardia vigente nell\u2019area protetta, delle norme anti Covid-19 e con un approccio PlasticFree, in linea con la campagna del Ministero della Transizione Ecologica, sposata dall\u2019Ente sin dal suo primo avvio.<\/p>\n<p>Univoco il pensiero del Presidente dott. Francesco Curcio e del Direttore f.f. ing. Domenico Cerminara: \u201cConfidiamo che, grazie al supporto dell\u2019Ente Parco, si possa garantire un\u2019auspicata ripartenza economica e sociale per il territorio silano, che non pu\u00f2 che essere declinata nell\u2019ottica di uno sviluppo ecosostenibile, che si basi sui principi del rispetto e della protezione dell\u2019immenso patrimonio naturale del Parco e che, finalmente, non \u00e8 pi\u00f9 vissuto come un vincolo, bens\u00ec come un\u2019occasione di crescita e rinascita\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pubblicata la graduatoria provvisoria degli ammessi a patrocinio oneroso ai sensi del bando pubblicato dall\u2019Ente Parco il 15 febbraio 2021<\/p>\n","protected":false},"author":42,"featured_media":151891,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-151890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=151890"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151890\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/151891"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=151890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=151890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=151890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}