{"id":151943,"date":"2021-06-25T04:50:56","date_gmt":"2021-06-25T02:50:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/vasto-incendio-si-propaga-per-15-ettari-ustionato-un-50enne\/"},"modified":"2023-01-16T17:35:22","modified_gmt":"2023-01-16T16:35:22","slug":"413012-vasto-incendio-si-propaga-per-15-ettari-ustionato-un-50enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/413012-vasto-incendio-si-propaga-per-15-ettari-ustionato-un-50enne\/","title":{"rendered":"Vasto incendio si propaga per 15 ettari, ustionato un 50enne"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>MONTEBELLO JONICO (RC) &#8211; Un vastissimo incendio ha interessato ieri contrada Molaro del Comune di Montebello Jonico. Sul posto 4 squadre dei Vigili del Fuoco, 20 uomini e 10 automezzi necessari per fronteggiare un fronte di fuoco propagatosi per circa <strong>15 ettari<\/strong>. Intervenuti in forza per proteggere alcune abitazioni con annessi ricoveri per animali dalle alte fiamme alimentate dal vento di scirocco e propagatesi per circa 15 ettari, i Vigili del Fuoco hanno anche soccorso un 50enne rimasto ustionato all&#8217;interno del proprio uliveto, mentre era intento a spegnere alcuni focolai.<\/p>\n<p>Viste le gravi condizioni dell&#8217;uomo i pompieri hanno costruito una barella di fortuna trasportandolo in un&#8217;area di pianura distante circa un chilometro dal punto dell&#8217;incidente dove, nel frattempo, era atterrato <strong>l&#8217;elisoccorso<\/strong>, che ha provveduto all&#8217;immediato trasporto verso il pi\u00f9 vicino centro ustionati. Ci sono volute oltre 12 ore per avere ragione delle fiamme e mettere in sicurezza le aree antropizzate. Sul posto anche Calabria Verde e Carabinieri. Per spegnere il vasto rogo sono intervenuti anche due Canadair in supporto alle squadre di terra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per domare l&#8217;incendio di vastissime proporzioni hanno lavorato 20 uomini e 10 automezzi dei Vigili del fuoco<\/p>\n","protected":false},"author":42,"featured_media":151944,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-151943","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=151943"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/151943\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/151944"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=151943"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=151943"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=151943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}