{"id":152329,"date":"2021-07-02T08:22:05","date_gmt":"2021-07-02T06:22:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/faisa-confail-ripristinare-il-tratto-della2-cosenza-altilia-grimaldi\/"},"modified":"2023-01-16T17:35:49","modified_gmt":"2023-01-16T16:35:49","slug":"413912-faisa-confail-ripristinare-il-tratto-della2-cosenza-altilia-grimaldi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/413912-faisa-confail-ripristinare-il-tratto-della2-cosenza-altilia-grimaldi\/","title":{"rendered":"Faisa Confail: &#8220;ripristinare il tratto dell&#8217;A2 Cosenza-Altilia Grimaldi&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Il tratto autostradale di competenza <strong>dell&#8217;Anas tra Cosenza e Altilia<\/strong> \u00e8 da troppo tempo soggetto a lavori di manutenzione e puntualmente alle porte della stagione estiva, vengono realizzati lavori con chiusure di diversi chilometri con conseguente senso doppio di circolazione. A tornare sui disagi \u00e8 il sindacato Faisa Confali che sottolinea come questa situazione faccia aumentare <strong>&#8220;il rischio di incidenti stradali,<\/strong> provocando non solo blocco alla circolazione ma soprattutto vittime. Su gran parte del tratto di strada non \u00e8 presente la corsia di emergenza e se un mezzo pesante, un autobus o qualsiasi altro genere di vettura abbia un&#8217;avaria che lo costringa all\u2019arresto immediato del mezzo, potrebbe verificarsi un blocco alla viabilit\u00e0, non essendoci neanche piazzole di sosta nelle vicinanze&#8221;.<\/p>\n<p>&#8220;Di recente si sono verificati anche incidenti e sicuramente la colpa non \u00e8 da attribuire solo ai lavori in corso d\u2019opera ma di certo la situazione la rende ancor pi\u00f9 difficoltosa&#8221;. Il sindacato esprime soddisfazione per i lavori di messa in sicurezza e le migliorie apportate sull\u2019A2, ma allo stesso tempo esprime preoccupazione per le continue interruzioni. Inoltre da qualche mese risulta che la maggior parte della strada ormai sia formata da doppi sensi di circolazione e deviazioni. <strong>Giunti ormai in piena stagione estiva, la possibilit\u00e0 di potersi spostare pi\u00f9 liberamente porter\u00e0 un flusso maggiore di rallentamenti sulla strada, ed un&#8217;alta probabilit\u00e0 di rischio incidenti, recando danni alla viabilit\u00e0, alle persone, ai mezzi e anche danni autostradali<\/strong>. Pertanto &#8211; conclude il sindacato &#8211; ci rivolgiamo alle autorit\u00e0 competenti al fine di intervenire, sempre nel rispetto dei lavori in atto sul tratto citato ma con la possibilit\u00e0 di avere pi\u00f9 fluidit\u00e0 di viabilit\u00e0. Inoltre riteniamo che gi\u00e0 la riduzione dei lavori renderebbe pi\u00f9 fluido il traffico veicolare&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con una richiesta all&#8217;assessore ai trasporti e alle infrastrutture Catalfamo il sindacato evidenzia ancora una volta la situazione che ormai perdura da anni<\/p>\n","protected":false},"author":42,"featured_media":152330,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-152329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=152329"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152329\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/152330"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=152329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=152329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=152329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}