{"id":152331,"date":"2021-07-02T08:35:37","date_gmt":"2021-07-02T06:35:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-incendio-sulla-collina-a-ridosso-della-statale-107\/"},"modified":"2023-01-16T17:35:49","modified_gmt":"2023-01-16T16:35:49","slug":"413915-rende-incendio-sulla-collina-a-ridosso-della-statale-107","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/413915-rende-incendio-sulla-collina-a-ridosso-della-statale-107\/","title":{"rendered":"Rende, incendio sulla collina a ridosso della Statale 107"},"content":{"rendered":"<p>RENDE &#8211; Incendio questa mattina nel territorio del <strong>Comune di Rende che attraversa la strada statale 107 Silana Crotonese<\/strong>. Sterpaglie e vegetazione a fuoco sulla collina di <strong>via Lussemburgo<\/strong>. Sul posto sono subito intervenuti i vigili del fuoco per evitare che il rogo arrivasse a lambire anche alcune abitazioni vicine. Al momento non si segnalano danni a persone ma gran parte della collina \u00e8 andata in fumo.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-413918 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/07\/incendio-collina-rende-su-statale-107.jpg\" alt=\"\" width=\"598\" height=\"446\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-413917 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/07\/incendio-collina-rende-su-statale-107-03.jpg\" alt=\"\" width=\"591\" height=\"369\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un incendio ha intressato la collina di Rende nei pressi della statale 107 in direzione Paola. In fiamme vegetazione e sterpaglie<\/p>\n","protected":false},"author":42,"featured_media":152332,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[],"class_list":["post-152331","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152331","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=152331"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152331\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/152332"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=152331"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=152331"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=152331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}