{"id":15273,"date":"2013-01-07T07:29:20","date_gmt":"2013-01-07T06:29:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=15273"},"modified":"2023-01-17T13:13:20","modified_gmt":"2023-01-17T12:13:20","slug":"4977-sindaco-catanzarola-destraa-supplettive-sostegno-ad-abramo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/4977-sindaco-catanzarola-destraa-supplettive-sostegno-ad-abramo\/","title":{"rendered":"Sindaco Catanzaro:&#8221;la destra&#8221;,a &#8220;supplettive&#8221; sostegno ad Abramo"},"content":{"rendered":"<p><strong>CATANZARO<\/strong> &#8211; &#8220;L&#8217;auspicio e&#8217; che alle suppletive del 20 e del 21 gennaio, gli oltre 6000 elettori chiamati ad esprimersi, ribadiscano la loro fiducia a Sergio Abramo, che gia&#8217; in passato e&#8217;<\/p>\n<p>  <!--more-->  <\/p>\n<p>stato il sindaco piu&#8217; votato d&#8217;Italia&#8221;. Lo afferma Domenico Furgiuele, segretario provinciale de &#8220;La Destra&#8221;. &#8220;Anche se non presente direttamente con una sua lista, il partito del candidato presidente alla regione Lazio per il centrodestra, &#8211; dice &#8211; ha dato mandato ai tesserati e ai simpatizzanti presenti in citta&#8217;, di sostenere ancora il candidato a sindaco del centro-destra. Abramo, dall&#8217;alto della sua esperienza, con la sua Giunta ha saputo da subito mettere su i binari del buon governo, una citta&#8217; disastrata da 5 anni di mala gestione. Considerato che tante e troppe sono le lacune da affrontate, per un capoluogo di regione degno di tale ruolo, e&#8217; necessario che &#8220;l&#8217;esperienza Abramo&#8221; riprenda con slancio da dove e&#8217; stata bruscamente interrotta. La Destra &#8211; conclude &#8211; e&#8217; certa che, le elezioni parziali relative alle otto sezioni, &#8220;spazzeranno&#8221; definitivamente dubbi e incertezze, e confermeranno anche in quei quartieri fiducia ad Abramo&#8221;.<\/p>\n<p>Fonte AGI<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; &#8220;L&#8217;auspicio e&#8217; che alle suppletive del 20 e del 21 gennaio, gli oltre 6000 elettori chiamati ad esprimersi, ribadiscano la loro fiducia a Sergio Abramo, che gia&#8217; in passato e&#8217;<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,18],"tags":[],"class_list":["post-15273","post","type-post","status-publish","format-standard","hentry","category-archivio-storico-news","category-dai-comuni"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=15273"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15273\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=15273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=15273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=15273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}