{"id":152824,"date":"2021-07-12T10:09:36","date_gmt":"2021-07-12T08:09:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/controlli-sul-tirreno-cosentino-un-arresto-per-droga-e-due-donne-denunciate\/"},"modified":"2023-01-16T17:36:24","modified_gmt":"2023-01-16T16:36:24","slug":"415040-controlli-sul-tirreno-cosentino-un-arresto-per-droga-e-due-donne-denunciate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/415040-controlli-sul-tirreno-cosentino-un-arresto-per-droga-e-due-donne-denunciate\/","title":{"rendered":"Controlli sul Tirreno cosentino, un arresto per droga e due donne denunciate"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>SCALEA (CS) &#8211; Oltre 150 autovetture controllate e 210 persone identificate. E da un controllo stradale che \u00e8 maturato <strong>l\u2019arresto di un 29enne pregiudicato di Tortora<\/strong> per detenzione ai fini di spaccio di sostanza stupefacente. Il ragazzo, nel tardo pomeriggio di venerd\u00ec, \u00e8 stato fermato sulla Statale 18 all\u2019altezza del Comune di <strong>Diamante<\/strong> mentre era passeggero a bordo dell\u2019autovettura condotta da un <strong>suo amico di origine campana<\/strong>.<\/p>\n<p>Insospettiti dall\u2019ingiustificato stato<strong> di agitazione di entrambi<\/strong>, i carabinieri di Scalea hanno proceduto ad una perquisizione personale e veicolare rinvenendo, occultati nelle mutande del giovane tortorese, un sacchetto trasparente contenente 5<strong>3 grammi di cocaina. <\/strong>Le analisi hanno permesso di accertare che dal quantitativo di sostanza stupefacente sequestrata, sulla base del principio attivo contenuto nello stesso, avrebbero potuto essere ricavate circa <strong>258 dosi<\/strong>, da destinare alla vendita al dettaglio, per un volume d\u2019affari superiore <strong>ai 3.000 euro.<\/strong><\/p>\n<p>Ieri sera invece, alle ore 20:30, i militari sono intervenuti a seguito di una richiesta al 112, nei pressi della Stazione Ferroviaria di Scalea dove si era consumato un <strong>acceso litigio tra due giovani donne<\/strong>, di cui una di origine straniera, culminato con il <strong>ferimento di due persone<\/strong>. La lite, scaturita per futili motivi, ha visto un\u2019iniziale scambio di <strong>calci e pugni molto animato tra le due donne<\/strong> sino a quando, la donna di origine straniera, ha estratto un coltello con il quale ha colpito la rivale ferendola al braccio sinistro. Il marito di quest\u2019ultima, nel frapporsi tra le stesse, nel disperato <strong>tentativo di bloccare la consorte \u00e8 stato anch\u2019egli ferito al braccio sinistro.<\/strong> Giunti sul posto i militari hanno trovato l\u2019arma da taglio, nel frattempo gettata in un vicino cestino della spazzatura, e contattato i sanitari del 118 che hanno medicato le lievi ferite riportate dai due malcapitati. Entrambe le donne sono state deferite in stato di libert\u00e0 alla competente Procura della Repubblica di Paola.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fine settimana movimentato sulla fascia costiera tirrenica, tra i comuni di Tortora e Bonifati, a cui si sono aggiunti i festeggiamenti dell\u2019Italia Campione d\u2019Europa. Un giovane arrestato a Diamante e due donne denunciate per rissa<\/p>\n","protected":false},"author":42,"featured_media":152825,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-152824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=152824"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/152825"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=152824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=152824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=152824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}