{"id":152832,"date":"2021-07-12T12:18:53","date_gmt":"2021-07-12T10:18:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/spaccio-e-guida-in-stato-di-ebbrezza-un-arresto-e-tre-violazioni-nel-cosentino\/"},"modified":"2023-01-16T17:36:24","modified_gmt":"2023-01-16T16:36:24","slug":"415057-spaccio-e-guida-in-stato-di-ebbrezza-un-arresto-e-tre-violazioni-nel-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/415057-spaccio-e-guida-in-stato-di-ebbrezza-un-arresto-e-tre-violazioni-nel-cosentino\/","title":{"rendered":"Spaccio e guida in stato di ebbrezza. Un arresto e tre violazioni nel cosentino"},"content":{"rendered":"<p>CORIGLIANO &#8211; ROSSANO (CS)\u00a0 &#8211; Nel fine settimana carabinieri di di Corigliano Calabro hanno tratto in arrestato un insospettabile <strong>26enne del posto per detenzione di sostanze stupefacenti<\/strong> ai fini di spaccio e <strong>sanzionato tre giovanissimi per guida in stato di ebbrezza alcolica<\/strong>.<\/p>\n<p>Sono stati i militari del Nucleo Operativo e Radiomobile a fermare un 26enne che si trovava alla guida del proprio scooter in compagnia di un noto pregiudicato del posto. Effettuato un controllo e una dettagliata perquisizione personale dei due, i militarti hanno rinvenuto una<strong> dose di cocaina nascosta nello zaino del guidatore<\/strong>. I carabinieri hanno cos\u00ec deciso di proseguire la perquisizione anche presso la sua abitazione, sita nello scalo coriglianese, dove \u00e8 stata rivenuta altra sostanza:\u00a0 nel cassetto di un mobile della stanza da letto del ragazzo \u00e8 stato trovato un <strong>borsello contenente diverse inflorescenze di marijuana<\/strong>, per un peso totale di circa 10 grammi, nonch\u00e9 un bilancino di precisione perfettamente funzionante per la pesatura della droga. Tutto il materiale \u00e8 stato sottoposto a sequestro penale, mentre per il 26enne sono scattate le manette per <strong>detenzione ai fini spaccio di sostanze stupefacenti<\/strong>.<\/p>\n<p>Dagli ulteriori accertamenti effettuati sul conto del ragazzo \u00e8 stato accertato, inoltre, che lo stesso non era in possesso della patente. Alla richiesta di spiegazioni il giovane si \u00e8 giustificato ai militari solo come dimenticanza, nascondendo in realt\u00e0 <strong>una sospensione in cui lo stesso era incorso nei mesi scorsi.<\/strong> Per tale motivo \u00e8 stato anche sanzionato con una salata <strong>multa ed il fermo del motociclo<\/strong>. Sempre nel fine settimana sono continuati i controlli per contrastare il pericoloso fenomeno della guida in stato di ebbrezza alcolica e grazie all\u2019utilizzo dell&#8217;etilometrico di ultima generazione in dotazione, sono stati<strong> controllati decine di giovanissimi <\/strong>e\u00a0accertate <strong>tre violazione nella sola notte fra sabato e domenica<\/strong>: tutti e tre neo-patentati, quindi titolari della patente di guida da meno di tre anni ovvero minori di anni 21, nei cui confronti vige un regime normativo pi\u00f9 rigido, che prevede sempre che il tasso alcomelico debba essere pari allo 0. I giovanissimi sono stati <strong>trovati con delle quantit\u00e0 di alcool comprese fra 0,46 g\/l e 0,76 g\/l<\/strong>, quindi nei loro confronti sono scattate le sanzioni del ritiro della patente, per la successiva sospensione e di salate sanzioni comminate in base alla gravit\u00e0 della violazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Controlli nel fine settimana e sanzioni scattate nei confronti di alcuni giovanissimi. Un 26enne arrestato per detenzione e spaccio<\/p>\n","protected":false},"author":55,"featured_media":152833,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-152832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=152832"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/152833"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=152832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=152832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=152832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}