{"id":152959,"date":"2021-07-14T12:51:14","date_gmt":"2021-07-14T10:51:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/aggredisce-prima-gli-operatori-del-118-e-poi-un-carabiniere-arrestato-38enne\/"},"modified":"2023-01-16T17:36:33","modified_gmt":"2023-01-16T16:36:33","slug":"415428-aggredisce-prima-gli-operatori-del-118-e-poi-un-carabiniere-arrestato-38enne","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/415428-aggredisce-prima-gli-operatori-del-118-e-poi-un-carabiniere-arrestato-38enne\/","title":{"rendered":"Aggredisce prima gli operatori del 118 e poi un carabiniere. Arrestato 38enne"},"content":{"rendered":"<p>CORIGLIANO &#8211; ROSSANo (CS) &#8211; I carabinieri di Corigliano Calabro hanno<strong> tratto in arresto per le ipotesi di reato di resistenza e minaccia aggravata a pubblico ufficiale<\/strong> un 38enne del posto. Allertati dalla locale Centrale Operativa, i militari sono arrivati in via Margherita, dove si trovava un uomo <strong>in escandescenze ed in evidente stato di alterazione psicofisica<\/strong>, dovuto verosimilmente ad un abuso di alcool. Lo stesso aveva pi\u00f9 volte<strong> aggredito verbalmente personale del 118<\/strong> che era intervenuto per prestargli le cure del caso.<\/p>\n<p>Arrivati sul posto, i carabinieri sono stati immediatamente fatti oggetto di minacce da parte del 38enne che,dopo <strong>aver afferrato in mano una bottiglia di vetro<\/strong> ed averla infranta, si \u00e8 scagliato contro un carabiniere per colpirlo. Solo la prontezza di riflessi di quest\u2019ultimo evitava il peggio. L\u2019uomo, con non poca difficolt\u00e0, \u00e8 stato bloccato e portato al locale pronto soccorso, dove, una volta visitato, \u00e8 stato dimesso. I carabinieri, quindi, hanno accompagnato l&#8217;uomo in caserma. A seguito della condotta tenuta, d\u2019intesa con la Procura della Repubblica di Castrovillari, \u00e8 stato <strong>tratto in arresto per i reati di resistenza e minaccia a pubblico ufficiale<\/strong>. Tradotto presso la sua abitazione in regime di arresti domiciliari, nella giornata odierna si \u00e8 celebrato il rito direttissimo, a seguito del quale il GIP ha convalidato l\u2019arresto, confermando la misura cautelare detentiva nei confronti dell\u2019indagato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo, in evidente stato di alterazione alcolica, dopo aver rotto un a bottiglia si \u00e8 scagliato contro un carabiniere per colpirlo<\/p>\n","protected":false},"author":55,"featured_media":152960,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-152959","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152959","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=152959"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/152959\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/152960"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=152959"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=152959"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=152959"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}