{"id":153235,"date":"2021-07-19T15:44:25","date_gmt":"2021-07-19T13:44:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/tragedia-sul-tirreno-cosentino-precipita-da-un-edificio-muore-operaio-di-58-anni\/"},"modified":"2023-01-16T17:36:51","modified_gmt":"2023-01-16T16:36:51","slug":"416153-tragedia-sul-tirreno-cosentino-precipita-da-un-edificio-muore-operaio-di-58-anni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/416153-tragedia-sul-tirreno-cosentino-precipita-da-un-edificio-muore-operaio-di-58-anni\/","title":{"rendered":"Tragedia sul Tirreno cosentino. Precipita da un edificio, muore operaio di 58 anni"},"content":{"rendered":"<p>BUONVICINO (CS) &#8211; Tragico incidente sul lavoro nel cosentino. Vittima \u00e8 un<strong> operaio di 58 anni,<\/strong> C.V. di Belvedere Marittimo, morto questo pomeriggio in contrada Lago a Buonvicino, comune del Tirreno, dopo essere accidentalmente<strong> caduto da un edificio<\/strong> in ristrutturazione a cui stava lavorando. <strong>Un volo terribile di diversi metri<\/strong>, che non ha lasciato scampo all&#8217;uomo, morto sul colpo, <strong>nonostante gli immediati soccorsi del 118<\/strong> che hanno solo potuto constatare solo il decesso.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/13386\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-416157\" src=\"https:\/\/quicosenza.it\/news\/13386\" alt=\"\" width=\"565\" height=\"365\" title=\"\"><\/a><\/p>\n<p>Per recuperare la salma dell&#8217;operaio sono <strong>intervenuti i vigili del fuoco del distaccamento di Scalea<\/strong> che stanno attendendo l&#8217;<strong>autorizzazione del magistrato. <\/strong>Sul posto i carabinieri che hanno avviato le indagini per accertare la dinamica del tragico incidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;uomo \u00e8 precipitato per diversi metri da un edificio in ristrutturazione a cui stava lavorando in contrada Lago a Buonvicino<\/p>\n","protected":false},"author":55,"featured_media":153236,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[19],"class_list":["post-153235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/153235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=153235"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/153235\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/153236"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=153235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=153235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=153235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}