{"id":153353,"date":"2021-07-21T12:40:32","date_gmt":"2021-07-21T10:40:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/regioni-in-giallo-con-20-e-30-di-intensive-e-ricoveri-pass-vedere-per-alcuni-eventi\/"},"modified":"2023-01-16T17:37:00","modified_gmt":"2023-01-16T16:37:00","slug":"416477-regioni-in-giallo-con-20-e-30-di-intensive-e-ricoveri-pass-vedere-per-alcuni-eventi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/416477-regioni-in-giallo-con-20-e-30-di-intensive-e-ricoveri-pass-vedere-per-alcuni-eventi\/","title":{"rendered":"Regioni &#8220;in giallo con 20% e 30% di intensive e ricoveri. Pass verde solo per alcuni eventi&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; Il Governo \u00e8 al lavoro per<strong> definire il nuovo decreto Covid<\/strong>, che dovr\u00e0 stabilire la <strong>proroga dello stato di emergenza,<\/strong> i criteri per decidere <strong>i &#8220;colori&#8221; delle regioni<\/strong> e le tanto attese <strong>norme per l&#8217;utilizzo del green pass<\/strong>. La cabina di regia e il Consiglio dei ministri per dare il via libera al provvedimento, secondo quanto si apprende da fonti di governo, dovrebbero tenersi domani, con uno slittamento di un giorno rispetto alla data di oggi inizialmente prevista. Nessuna delle due riunioni, per\u00f2, al momento \u00e8 stata confermata. Per quanto riguarda la proroga dello stato di emergenza (in scadenza il 31 luglio) <strong>l&#8217;orientamento sarebbe quello di portare il termine al prossimo 31 dicembre<\/strong>, quando sar\u00e0 possibile fare un punto sulla pandemia a campagna di vaccinazione conclusa. Sicuramente saranno <strong>cambiati i criteri per la definizione delle zone<\/strong> (bianca, gialla, arancione, rossa) delle Regioni. Dovrebbero essere abbandonati i parametri relativi ai contagi e all&#8217;incidenza, in favore di un conteggio basato su ospedalizzazioni e occupazione delle terapie intensive, anche in relazione all&#8217;andamento delle vaccinazioni.<\/p>\n<p>&nbsp;<\/p>\n<h4>I nuovi parametri chiesti dalle Regioni<\/h4>\n<p><strong>Si resta in zona bianca se l&#8217;occupazione delle terapie intensive non supera il 20%<\/strong> dei posti letto a disposizione e se quella dei r<strong>eparti ordinari non supera il 30%.<\/strong> E&#8217; questa la proposta della Conferenza delle Regioni al governo in vista della revisione dei parametri del monitoraggio &#8220;in un&#8217;ottica &#8211; dice il presidente Massimiliano Fedriga <strong>&#8211; di collaborazione istituzionale&#8221;<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/13405\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-359780\" src=\"https:\/\/quicosenza.it\/news\/13405\" alt=\"\" width=\"541\" height=\"304\" title=\"\"><\/a><\/p>\n<h4>Green pass solo per eventi non consentiti<\/h4>\n<p>&#8216;C&#8217;\u00e8 infine il capitolo green pass, quello pi\u00f9 controverso, in particolare per l&#8217;opposizione della Lega alle restrizioni. Potrebbe essere<strong> mantenuto il rilascio dopo la prima dose<\/strong>, ma con un &#8220;pressing&#8221; a completare il ciclo entro breve tempo. Inoltre potrebbero essere in<strong>dividuate tipologie di luoghi, attivit\u00e0, eventi,<\/strong> a cui per partecipare sar\u00e0 necessario esibire il green pass. In base alla &#8220;categoria di rischio&#8221;, per alcuni sar\u00e0 sufficiente avere ricevuto la prima dose, per altri (come i grandi eventi) ne serviranno due. Anche su questo i governatori hanno avanzato oggi la loro proposta chiedendo che <strong>il pass verde venga utilizzato &#8220;per permettere la ripresa di attivit\u00e0 fino ad oggi non consentite<\/strong>&#8221; come &#8220;eventi sportivi e di spettacolo, discoteche, fiere e congressi&#8221;. Le proposte, sottolinea ancora Fedriga, sono state elaborate anche &#8220;alla luce dell&#8217;a<strong>ttuale contesto epidemiologico,<\/strong> caratterizzato da un aumento dell&#8217;incidenza ma da una<strong> bassa occupazione dei posti letto ospedalieri,<\/strong> e dalla progressione intensa della campagna vaccinale. Si tratta &#8211; aggiunge &#8211; di <strong>proposte che facciamo al Governo<\/strong>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Regioni chiederanno al Governo l&#8217;uso del green pass per &#8220;la ripresa in sicurezza di attivit\u00e0 fino a oggi non consentite o limitate&#8221;<\/p>\n","protected":false},"author":55,"featured_media":153354,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-153353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/153353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=153353"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/153353\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/153354"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=153353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=153353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=153353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}