{"id":15337,"date":"2013-01-08T12:34:07","date_gmt":"2013-01-08T11:34:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=15337"},"modified":"2023-01-17T13:13:27","modified_gmt":"2023-01-17T12:13:27","slug":"5049-nel-2012-pil-pro-capite-ridotto-del-16","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5049-nel-2012-pil-pro-capite-ridotto-del-16\/","title":{"rendered":"Nel 2012 Pil pro capite ridotto del 1,6%"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>CATANZARO<\/strong> &#8211;&nbsp;In Calabria nel 2012 il Pil pro capite si e&#8217; attestato a 13.392 , con una flessione dell&#8217;1,6%, piu&#8217; contenuta rispetto alla media<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">nazionale. E&#8217; quanto emerge dalla diciottesima edizione dell&#8217;Osservatorio di Findomestic Banca sul consumo di beni durevoli in Calabria. Catanzaro fa registrare la miglior performance in termini di reddito, con 14.334. Crotone e Vibo Valentia sono tra le provincie d&#8217;Italia che hanno segnato una minor riduzione del Pil pro capite.&nbsp;<\/p>\n<p style=\"text-align: justify;\">(Fonte ANSA)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211;&nbsp;In Calabria nel 2012 il Pil pro capite si e&#8217; attestato a 13.392 , con una flessione dell&#8217;1,6%, piu&#8217; contenuta rispetto alla media<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-15337","post","type-post","status-publish","format-standard","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=15337"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15337\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=15337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=15337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=15337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}