{"id":15338,"date":"2013-01-08T12:45:37","date_gmt":"2013-01-08T11:45:37","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=15338"},"modified":"2023-01-17T13:13:27","modified_gmt":"2023-01-17T12:13:27","slug":"5050-assemblea-di-fine-anno-per-volare-a-santo-stefano","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/5050-assemblea-di-fine-anno-per-volare-a-santo-stefano\/","title":{"rendered":"Assemblea di fine anno per &#8220;Volare a Santo Stefano&#8221;"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>RENDE<\/strong> &#8211; Presso la sede dell\u2019Associazione \u201cVolare a Santo Stefano\u201d in Rende, nei giorni scorsi si \u00e8 tenuta l\u2019assemblea di fine anno per fare il punto sulle attivit\u00e0<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">svolte nell\u2019anno 2012 e quelle da intraprendere nell\u2019anno 2013. Il Presidente Maria Brunella Stancato nel suo intervento ha relazionato ai soci intervenuti sugli eventi svolti, sia in campo sociale, sia in campo culturale, in Italia e all\u2019estero. In campo sociale ha precisato il Presidente per tutto l\u2019anno si \u00e8 continuato a svolgere il servizio del banco alimentare rivolto alle famiglie pi\u00f9 bisognose della zona con l\u2019aiuto di tanti volontari del posto, mentre, per quanto riguarda la parte culturale svolta tramite gli scambi culturali o gemellaggi con paesi rientranti nella C.E. e finanziati dalla stessa, si sono rinforzati i rapporti con la Romania ,dove l\u2019associazione si \u00e8 recata per tre volte nell\u2019anno appena trascorso, con la Bulgaria e la Lettonia. Per quanto riguarda il 2013, il Presidente ha confermato il servizio del banco alimentare, gli scambi culturali nonch\u00e9 nuove iniziative per quanto riguarda corsi di formazione alle imprese e un partenariato con una Societ\u00e0 rumena rivolto alla promozione delle eccellenze enogastronomiche calabresi. Dopo il Presidente, ha preso la parola il segretario Antonio Volpentesta che ha reso noto ai soci l\u2019andamento economico dell\u2019associazione che chiuder\u00e0, anche se ancora non pronto, il 2012, con un bilancio in parit\u00e0. Infine sono intervenuti alcuni soci che si sono detti molto soddisfatti delle attivit\u00e0 svolte nell\u2019anno precedente ed hanno augurato a tutta l\u2019Associazione nuovi traguardi per l\u2019anno che \u00e8 appena iniziato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Presso la sede dell\u2019Associazione \u201cVolare a Santo Stefano\u201d in Rende, nei giorni scorsi si \u00e8 tenuta l\u2019assemblea di fine anno per fare il punto sulle attivit\u00e0<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-15338","post","type-post","status-publish","format-standard","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=15338"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/15338\/revisions"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=15338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=15338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=15338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}