{"id":153417,"date":"2021-07-22T13:26:09","date_gmt":"2021-07-22T11:26:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/elezioni-amministrative-giacomo-mancini-io-ci-sono\/"},"modified":"2023-01-16T17:37:03","modified_gmt":"2023-01-16T16:37:03","slug":"416617-elezioni-amministrative-giacomo-mancini-io-ci-sono","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/416617-elezioni-amministrative-giacomo-mancini-io-ci-sono\/","title":{"rendered":"Elezioni, Giacomo Mancini risponde all&#8217;appello dei riformisti &#8220;per Cosenza io ci sono&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Giacomo Mancini<\/strong> risponde all\u2019appello della Piattaforma riformista che raccoglie l\u2019area socialista, dove viene indicato candidato ideale a sindaco della citt\u00e0 di Cosenza. Mancini con un perentorio \u201c<strong>per la citt\u00e0 di Cosenza e per i cosentini io ci sono<\/strong>\u201d e si dice dunque <strong>disponibile ad una sua candidatura<\/strong> a futuro sindaco della citt\u00e0 per la coalizione del centrosinistra.<\/p>\n<p>L\u2019<a href=\"https:\/\/quicosenza.it\/news\/13414\" target=\"_blank\" rel=\"noopener\">invito e l&#8217;appello<\/a> a scendere in campo, lo ricordiamo, \u00e8 stato sottoscritto dalle Associazioni Laboratorio Riformista Calabrese, LabDem, Centro Studio \u201cPetronio\u201d, Federazione Riformista di Rende, Circolo \u201cAvanti\u201d Giacomo Mancini di Cosenza, Associazione \u201cSalvemini\u201d, Forum Riformista Cosenza e Circolo Socialista \u201cVincenzo Gallizzi\u201d. Per i sottoscrittori dell&#8217;appello, <strong>Giacomo Mancini \u00e8 il candidato giusto per guidare il centrosinistra di Cosenza<\/strong>, per allargare i confini della coalizione e per competere per vincere alle ormai prossime elezioni comunali\u201d. Una figura che<strong>\u00a0pu\u00f2 vantare esperienza, competenza, passione, capacit\u00e0 di interlocuzione e correttezza amministrativa<\/strong>. \u201cIn pi\u00f9 \u2013 \u00e8 stato riportato nella nota di ieri &#8211; rappresenta degnamente la nobile storia socialista che in citt\u00e0 ha radici profonde e ancora rigogliose. <strong>Una storia che a Cosenza, a Rende nell\u2019area urbana e in Calabria ha fulgidi esempi di amministratori concreti e lungimiranti<\/strong> con la cui visione hanno saputo immaginare e realizzare lo sviluppo della nostra comunit\u00e0\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per la Piattaforma riformista, Giacomo Mancini \u00e8 il candidato giusto per guidare il centrosinistra nella citt\u00e0 di Cosenza<\/p>\n","protected":false},"author":59,"featured_media":153418,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[135],"class_list":["post-153417","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/153417","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=153417"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/153417\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/153418"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=153417"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=153417"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=153417"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}