{"id":154156,"date":"2021-08-06T12:37:41","date_gmt":"2021-08-06T10:37:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/trebisacce-giovane-insospettabile-trovato-con-la-droga-in-casa-arrestato\/"},"modified":"2023-01-16T17:37:53","modified_gmt":"2023-01-16T16:37:53","slug":"418376-trebisacce-giovane-insospettabile-trovato-con-la-droga-in-casa-arrestato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/418376-trebisacce-giovane-insospettabile-trovato-con-la-droga-in-casa-arrestato\/","title":{"rendered":"Trebisacce: giovane insospettabile trovato con la droga in casa, arrestato"},"content":{"rendered":"<p>TREBISACCE (CS) \u2013 I carabinieri di Corigliano Calabro hanno arrestato un ventunenne di Trebisacce per detenzione di sostanza stupefacente ai fini di spaccio dopo un intervento per altri motivi, non legati alla droga, nell&#8217;abitazione dove il giovane vive con i genitori. I militari sono stati infatti attirati dall\u2019odore acre ed hanno avviato una minuziosa perquisizione domiciliare.<\/p>\n<p>Nella sua stanza da letto, oltre al materiale tipicamente usato per il confezionamento ed il taglio della droga, \u00e8 stato trovato un bilancino di precisione perfettamente funzionante e sostanza da taglio. Le operazioni di ricerca sono proseguite in tutta la casa e in cucina, in un contenitore, sono state trovate nove dosi di hashish gi\u00e0 pronte per la vendita e residui di cocaina.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Considerato il materiale, la sostanza da taglio e la droga, \u00e8 stata ipotizzata l&#8217;attivit\u00e0 di spaccio da parte del ragazzo<\/p>\n","protected":false},"author":42,"featured_media":154157,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572,28],"tags":[],"class_list":["post-154156","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=154156"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154156\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/154157"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=154156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=154156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=154156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}