{"id":154292,"date":"2021-08-09T16:00:11","date_gmt":"2021-08-09T14:00:11","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-fiamme-minacciano-ancora-il-centro-storico-e-il-cimitero\/"},"modified":"2023-01-16T17:38:02","modified_gmt":"2023-01-16T16:38:02","slug":"418682-rende-fiamme-minacciano-ancora-il-centro-storico-e-il-cimitero","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/418682-rende-fiamme-minacciano-ancora-il-centro-storico-e-il-cimitero\/","title":{"rendered":"Paura a Rende, fiamme minacciano ancora il centro storico e il cimitero"},"content":{"rendered":"<p>RENDE &#8211; Due fronti di fuoco minacciano la colline che portano al centro storico e al cimitero di Rende. In questo momento le fiamme stanno interessando due aree collinari e sono vicine alle abitazioni, anche rurali. L&#8217;incendio si \u00e8 anche vicino all&#8217;area cimiteriale. Il vasto fronte di fuoco sta colpendo in particolare contrada Muttoli e sta camminando velocemente lungo una collina. Le fiamme sono <strong>sono alimentate dal forte vento caldo<\/strong> che soffia nella zona. Paura tra i residenti della zona a causa delle fiammate violente, che stanno cercando con mezzi propri e con pompe d&#8217;acqua di tenere lontano il fuoco.<\/p>\n<p>Allertati i vigili del fuoco sono sul posto nonostante in queste ore stiano lavorando incessantemente su numerosi incendi nel territorio cosentino. La zona vecchia di Rende ancora si lecca le ferite dopo<a href=\"https:\/\/quicosenza.it\/news\/13493\" target=\"_blank\" rel=\"noopener\"> l&#8217;incendio lo scorso 1 agosto<\/a>\u00a0che ha interessato abitazioni e un&#8217;attivit\u00e0 di ristorazione andata distrutta.<\/p>\n<p><strong><span style=\"color: #ff0000;\">Aggiornamento\u00a0<\/span><\/strong><\/p>\n<p>Sul posto vigili del fuoco e un&#8217;autobotte di Calabria Verde hanno quasi spento il fuoco e stanno lavorando ai piccoli focolai.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-418695 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/08\/Incendio-Rende-03.jpg\" alt=\"\" width=\"543\" height=\"428\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-418688 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/08\/Incendio-Rende-01.jpg\" alt=\"\" width=\"532\" height=\"325\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-418689 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/08\/Incendio-Rende-cimitero.jpg\" alt=\"\" width=\"547\" height=\"426\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-418686 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2021\/08\/Incendio-Rende.jpg\" alt=\"\" width=\"539\" height=\"337\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non c&#8217;\u00e8 pace sul fronte incendi. Ancora una volta bruciano le colline a ridosso del centro storico di Rende, gi\u00e0 duramente colpito nei giorni scorsi<\/p>\n","protected":false},"author":42,"featured_media":154293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19,135],"class_list":["post-154292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina","tag-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=154292"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/154292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/154293"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=154292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=154292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=154292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}